{"id":103,"count":1,"description":"","link":"https:\/\/kosovaideas.com\/sq\/product-category\/arti-dhe-kultura\/teater\/","name":"Teater","slug":"teater","taxonomy":"product_cat","parent":93,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Teater Archives - KOSOVA ideas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kosovaideas.com\/product-category\/arts-and-culture\/theater\/\" \/>\n<meta property=\"og:locale\" content=\"sq_AL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Teater Archives - KOSOVA ideas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kosovaideas.com\/product-category\/arts-and-culture\/theater\/\" \/>\n<meta property=\"og:site_name\" content=\"KOSOVA ideas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/product-category\\\/arts-and-culture\\\/theater\\\/\",\"url\":\"https:\\\/\\\/kosovaideas.com\\\/product-category\\\/arts-and-culture\\\/theater\\\/\",\"name\":\"Teater Archives - KOSOVA ideas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/product-category\\\/arts-and-culture\\\/theater\\\/#breadcrumb\"},\"inLanguage\":\"sq-AL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/product-category\\\/arts-and-culture\\\/theater\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kosovaideas.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arts and Culture\",\"item\":\"https:\\\/\\\/kosovaideas.com\\\/product-category\\\/arts-and-culture\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Theater\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/#website\",\"url\":\"https:\\\/\\\/kosovaideas.com\\\/\",\"name\":\"KOSOVA ideas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kosovaideas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sq-AL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/#organization\",\"name\":\"KOSOVA ideas\",\"url\":\"https:\\\/\\\/kosovaideas.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sq-AL\",\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kosovaideas.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/KosovaIdeas_Primary_Logo_Horizontal.png\",\"contentUrl\":\"https:\\\/\\\/kosovaideas.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/KosovaIdeas_Primary_Logo_Horizontal.png\",\"width\":1767,\"height\":300,\"caption\":\"KOSOVA ideas\"},\"image\":{\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teater Archives - KOSOVA ideas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kosovaideas.com\/product-category\/arts-and-culture\/theater\/","og_locale":"sq_AL","og_type":"article","og_title":"Teater Archives - KOSOVA ideas","og_url":"https:\/\/kosovaideas.com\/product-category\/arts-and-culture\/theater\/","og_site_name":"KOSOVA ideas","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/kosovaideas.com\/product-category\/arts-and-culture\/theater\/","url":"https:\/\/kosovaideas.com\/product-category\/arts-and-culture\/theater\/","name":"Teater Archives - KOSOVA ideas","isPartOf":{"@id":"https:\/\/kosovaideas.com\/#website"},"breadcrumb":{"@id":"https:\/\/kosovaideas.com\/product-category\/arts-and-culture\/theater\/#breadcrumb"},"inLanguage":"sq-AL"},{"@type":"BreadcrumbList","@id":"https:\/\/kosovaideas.com\/product-category\/arts-and-culture\/theater\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kosovaideas.com\/"},{"@type":"ListItem","position":2,"name":"Arts and Culture","item":"https:\/\/kosovaideas.com\/product-category\/arts-and-culture\/"},{"@type":"ListItem","position":3,"name":"Theater"}]},{"@type":"WebSite","@id":"https:\/\/kosovaideas.com\/#website","url":"https:\/\/kosovaideas.com\/","name":"KOSOVA ideas","description":"","publisher":{"@id":"https:\/\/kosovaideas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kosovaideas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sq-AL"},{"@type":"Organization","@id":"https:\/\/kosovaideas.com\/#organization","name":"KOSOVA ideas","url":"https:\/\/kosovaideas.com\/","logo":{"@type":"ImageObject","inLanguage":"sq-AL","@id":"https:\/\/kosovaideas.com\/#\/schema\/logo\/image\/","url":"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/KosovaIdeas_Primary_Logo_Horizontal.png","contentUrl":"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/KosovaIdeas_Primary_Logo_Horizontal.png","width":1767,"height":300,"caption":"KOSOVA ideas"},"image":{"@id":"https:\/\/kosovaideas.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kosovaideas.com\/sq\/wp-json\/wp\/v2\/product_cat\/103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kosovaideas.com\/sq\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/kosovaideas.com\/sq\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/kosovaideas.com\/sq\/wp-json\/wp\/v2\/product_cat\/93"}],"wp:post_type":[{"href":"https:\/\/kosovaideas.com\/sq\/wp-json\/wp\/v2\/product?product_cat=103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}