{"id":7248,"date":"2021-11-24T13:58:07","date_gmt":"2021-11-24T12:58:07","guid":{"rendered":"https:\/\/ki2023.kosovaideas.com\/product\/music-4-all\/"},"modified":"2023-07-17T10:21:51","modified_gmt":"2023-07-17T09:21:51","slug":"music-4-all","status":"publish","type":"product","link":"https:\/\/kosovaideas.com\/fr\/product\/music-4-all\/","title":{"rendered":"MUSIC 4 ALL"},"content":{"rendered":"<p><strong>Qui sommes-nous?<\/strong><\/p>\n<p>Je m&rsquo;appelle Jimmy Mustafa et je fais partie d&rsquo;un groupe de musique Rom appel\u00e9 \u00ab\u00a0Jimmy Mustafa Band\u00a0\u00bb de Plementina. Plemetina est une petite ville de la municipalit\u00e9 d&rsquo;Obiliq, \u00e0 Prishtina. C&rsquo;est un lieu multiethnique o\u00f9 cohabitent Albanais, Serbes, Roms, Ashkali et autres. En 2009, six jeunes Roms ont uni leurs talents pour cr\u00e9er un genre diff\u00e9rent de musique traditionnelle rom et d&rsquo;autres styles de musique. Nous avons deux albums studio, le premier intitul\u00e9\u00a0<strong>\u00ab\u00a0Posvetime\u00a0\u00bb (D\u00e9di\u00e9<\/strong>) avec 10 titres et le second album \u00ab\u00a0<strong>Romane Bajrakja\u00a0\u00bb (Drapeaux Roms)<\/strong>\u00a0avec 11 chansons originales. En 2018 et 2019, le groupe a effectu\u00e9 une tourn\u00e9e en Suisse et en Allemagne.<\/p>\n<p>J&rsquo;ai \u00e9galement produit la musique de neuf films documentaires sur les Roms, tels que : Jek Kham Jek Sel, Naci Palem Khere, Sar Thuv, Live, Auschvic en Pologne, Roki, etc. J&rsquo;ai travaill\u00e9 avec des enfants en tant que professeur, leur apprenant \u00e0 jouer d&rsquo;instruments tels que la guitare, le cajon, le piano, et leur donnant des cours de chant. Je suis le fondateur d&rsquo;un centre pour les enfants et les jeunes, avec des amis du Kosovo et de la Suisse, appel\u00e9 Music 4 All.<\/p>\n<p><strong>Quel est notre objectif?<\/strong><\/p>\n<p>Notre centre \u00ab\u00a0Music 4 ALL\u00a0\u00bb sera une initiative pionni\u00e8re et des plus abouties qui permettra aux enfants et aux jeunes d&rsquo;\u00e9largir leurs activit\u00e9s musicales et artistiques et de se d\u00e9couvrir de nouveaux talents. Music 4 ALL \u00e9tait et restera un second foyer pour chaque enfant et chaque jeune. Tous ceux qui aiment l&rsquo;art de la musique et qui veulent apprendre ou am\u00e9liorer le chant et la pr\u00e9formation aux \u00e9tudes feront partie de ce projet.<\/p>\n<p>Music 4 ALL proposera des cours individuels et collectifs de musique classique et moderne tels que le piano, la clarinette, le cajon, la guitare, le chant, le sport, l&rsquo;enregistrement vid\u00e9o, le montage vid\u00e9o et d&rsquo;autres activit\u00e9s n\u00e9cessaires aux enfants et aux jeunes. Il y aura \u00e9galement une classe d&rsquo;art\/peinture o\u00f9 les enfants cr\u00e9eront de l&rsquo;art \u00e0 travers la musique avec notre aide.<\/p>\n<p>Nous aurons \u00e9galement des ateliers, o\u00f9 des artistes seront invit\u00e9s \u00e0 partager leurs exp\u00e9riences avec tout le monde. Nous enregistrerons de la musique (chansons\/albums) et organiserons \u00e9galement des concerts\/\u00e9v\u00e9nements, o\u00f9 tout le monde sera le bienvenu.<\/p>\n<p><strong>Comment votre soutien va-t-il nous aider?<\/strong><\/p>\n<p>Gr\u00e2ce \u00e0 votre soutien, nous donnerons aux enfants et aux jeunes de Plementina la possibilit\u00e9 de montrer leur talent en musique et en arts.<\/p>\n<p>Nous organiserons les activit\u00e9s suivantes :<\/p>\n<ul>\n<li>\u00c9ducation musicale<\/li>\n<li>Cours de piano<\/li>\n<li>Cours de clarinette<\/li>\n<li>Classes de chant\/voix<\/li>\n<li>Cours de guitare<\/li>\n<li>Cours de cajon<\/li>\n<li>Cours d&rsquo;informatique<\/li>\n<li>Cin\u00e9ma (diffusion de films)<\/li>\n<li>Cours de peinture<\/li>\n<\/ul>\n<p>Il y aura cinq cours proposant des ateliers de guitare, clarinette, piano, cajon et chant. Ces cours seront dispens\u00e9s afin d&rsquo;enrichir et d&rsquo;\u00e9tendre la partie pratique, permettant aux candidats d&rsquo;acqu\u00e9rir les notes et les comp\u00e9tences de base dans les instruments ainsi que le chant.<\/p>\n<p><strong>Budget<\/strong><\/p>\n<p>Total\u00a0\u20ac 5\u00a0000,00<\/p>\n<table width=\"509\">\n<tbody>\n<tr>\n<td width=\"29\">1)<\/td>\n<td width=\"388\">\u00a0Mat\u00e9riel p\u00e9dagogique<\/td>\n<td width=\"92\">\u00a0\u20ac 200,00<\/td>\n<\/tr>\n<tr>\n<td>2)<\/td>\n<td>\u00a0Mat\u00e9riel p\u00e9dagogique<\/td>\n<td>\u00a0\u20ac 120,00<\/td>\n<\/tr>\n<tr>\n<td>3)<\/td>\n<td>\u00a0Mat\u00e9riel artistique pour les enfants<\/td>\n<td>\u00a0\u20ac 150,00<\/td>\n<\/tr>\n<tr>\n<td>4)<\/td>\n<td>\u00a0Collations pour les enfants<\/td>\n<td>\u00a0\u20ac 500,00<\/td>\n<\/tr>\n<tr>\n<td>5)<\/td>\n<td>\u00a0Transport hebdomadaire de Plementina \u00e0 Obiliq et Prishtina<\/td>\n<td>\u00a0\u20ac 600,00<\/td>\n<\/tr>\n<tr>\n<td>6)<\/td>\n<td>\u00a0PC pour le montage<\/td>\n<td>\u00a0\u20ac 800,00<\/td>\n<\/tr>\n<tr>\n<td>7)<\/td>\n<td>\u00a0Appareil photo<\/td>\n<td>\u00a0\u20ac 750,00<\/td>\n<\/tr>\n<tr>\n<td>8)<\/td>\n<td>\u00a0\u00c9v\u00e9nements suppl\u00e9mentaires, concerts<\/td>\n<td>\u00a0\u20ac 880,00<\/td>\n<\/tr>\n<tr>\n<td>9)<\/td>\n<td>\u00a0Chauffage<\/td>\n<td>\u00a0\u20ac 500,00<\/td>\n<\/tr>\n<tr>\n<td>10)<\/td>\n<td>\u00a010% de frais de carte de cr\u00e9dit, de virement bancaire et de plateforme<\/td>\n<td>\u00a0\u20ac 500,00<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<div class=\"description\">MUSIC 4 ALL est une \u00e9cole de musique \u00e0 Plementina. Nous offrons des cours gratuits pour tous les enfants et les jeunes.<\/div>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n","protected":false},"author":1429,"featured_media":6343,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[94],"product_tag":[],"class_list":{"0":"post-7248","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-arts-et-culture","8":"first","9":"instock","10":"sold-individually","11":"shipping-taxable","12":"purchasable","13":"product-type-crowdfunding"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MUSIC 4 ALL - KOSOVA ideas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kosovaideas.com\/fr\/produit\/music-4-all\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MUSIC 4 ALL - KOSOVA ideas\" \/>\n<meta property=\"og:description\" content=\"MUSIC 4 ALL est une \u00e9cole de musique \u00e0 Plementina. Nous offrons des cours gratuits pour tous les enfants et les jeunes. \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kosovaideas.com\/fr\/produit\/music-4-all\/\" \/>\n<meta property=\"og:site_name\" content=\"KOSOVA ideas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-17T09:21:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885.png\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"443\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/fr\\\/produit\\\/music-4-all\\\/\",\"url\":\"https:\\\/\\\/kosovaideas.com\\\/fr\\\/produit\\\/music-4-all\\\/\",\"name\":\"MUSIC 4 ALL - KOSOVA ideas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/fr\\\/produit\\\/music-4-all\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/fr\\\/produit\\\/music-4-all\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kosovaideas.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/1_664_885.png\",\"datePublished\":\"2021-11-24T12:58:07+00:00\",\"dateModified\":\"2023-07-17T09:21:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/fr\\\/produit\\\/music-4-all\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kosovaideas.com\\\/fr\\\/produit\\\/music-4-all\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/fr\\\/produit\\\/music-4-all\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kosovaideas.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/1_664_885.png\",\"contentUrl\":\"https:\\\/\\\/kosovaideas.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/1_664_885.png\",\"width\":730,\"height\":443},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/fr\\\/produit\\\/music-4-all\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kosovaideas.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/kosovaideas.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MUSIC 4 ALL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/#website\",\"url\":\"https:\\\/\\\/kosovaideas.com\\\/\",\"name\":\"KOSOVA ideas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kosovaideas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/#organization\",\"name\":\"KOSOVA ideas\",\"url\":\"https:\\\/\\\/kosovaideas.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kosovaideas.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/KosovaIdeas_Primary_Logo_Horizontal.png\",\"contentUrl\":\"https:\\\/\\\/kosovaideas.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/KosovaIdeas_Primary_Logo_Horizontal.png\",\"width\":1767,\"height\":300,\"caption\":\"KOSOVA ideas\"},\"image\":{\"@id\":\"https:\\\/\\\/kosovaideas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MUSIC 4 ALL - KOSOVA ideas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kosovaideas.com\/fr\/produit\/music-4-all\/","og_locale":"fr_FR","og_type":"article","og_title":"MUSIC 4 ALL - KOSOVA ideas","og_description":"MUSIC 4 ALL est une \u00e9cole de musique \u00e0 Plementina. Nous offrons des cours gratuits pour tous les enfants et les jeunes. \u00a0","og_url":"https:\/\/kosovaideas.com\/fr\/produit\/music-4-all\/","og_site_name":"KOSOVA ideas","article_modified_time":"2023-07-17T09:21:51+00:00","og_image":[{"width":730,"height":443,"url":"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kosovaideas.com\/fr\/produit\/music-4-all\/","url":"https:\/\/kosovaideas.com\/fr\/produit\/music-4-all\/","name":"MUSIC 4 ALL - KOSOVA ideas","isPartOf":{"@id":"https:\/\/kosovaideas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kosovaideas.com\/fr\/produit\/music-4-all\/#primaryimage"},"image":{"@id":"https:\/\/kosovaideas.com\/fr\/produit\/music-4-all\/#primaryimage"},"thumbnailUrl":"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885.png","datePublished":"2021-11-24T12:58:07+00:00","dateModified":"2023-07-17T09:21:51+00:00","breadcrumb":{"@id":"https:\/\/kosovaideas.com\/fr\/produit\/music-4-all\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kosovaideas.com\/fr\/produit\/music-4-all\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kosovaideas.com\/fr\/produit\/music-4-all\/#primaryimage","url":"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885.png","contentUrl":"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885.png","width":730,"height":443},{"@type":"BreadcrumbList","@id":"https:\/\/kosovaideas.com\/fr\/produit\/music-4-all\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kosovaideas.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/kosovaideas.com\/shop\/"},{"@type":"ListItem","position":3,"name":"MUSIC 4 ALL"}]},{"@type":"WebSite","@id":"https:\/\/kosovaideas.com\/#website","url":"https:\/\/kosovaideas.com\/","name":"KOSOVA ideas","description":"","publisher":{"@id":"https:\/\/kosovaideas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kosovaideas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/kosovaideas.com\/#organization","name":"KOSOVA ideas","url":"https:\/\/kosovaideas.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kosovaideas.com\/#\/schema\/logo\/image\/","url":"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/KosovaIdeas_Primary_Logo_Horizontal.png","contentUrl":"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/KosovaIdeas_Primary_Logo_Horizontal.png","width":1767,"height":300,"caption":"KOSOVA ideas"},"image":{"@id":"https:\/\/kosovaideas.com\/#\/schema\/logo\/image\/"}}]}},"column":"2","wpcf_product":{"display_name":"Xhemajl Jimmy Mustafa","location":"","funding_goal":"","total_raised":"5075","raised_percent":"0%","desc":"Qui sommes-nous?\r\n\r\n","days_remaining":"0","product_thumb":"<img width=\"300\" height=\"300\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885-300x300.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"MUSIC 4 ALL\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885-300x300.png 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885-150x150.png 150w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885-100x100.png 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>"},"wpcf_dashboard":"<div class=\"woocommerce\"><div class=\"woocommerce-info\">Veuillez d\u2019abord vous identifier\u00a0? <a class=\"wpneoShowLogin\" href=\"#\">Cliquez ici pour vous identifier<\/a><\/div><div class=\"wpneo_login_form_div\" style=\"display: none;\"><form name=\"loginform\" id=\"loginform\" action=\"https:\/\/kosovaideas.com\/fr\/wp-login.php\" method=\"post\"><p class=\"login-username\">\n\t\t\t\t<label for=\"user_login\">Identifiant ou adresse e-mail<\/label>\n\t\t\t\t<input type=\"text\" name=\"log\" id=\"user_login\" autocomplete=\"username\" class=\"input\" value=\"\" size=\"20\" \/>\n\t\t\t<\/p><p class=\"login-password\">\n\t\t\t\t<label for=\"user_pass\">Mot de passe<\/label>\n\t\t\t\t<input type=\"password\" name=\"pwd\" id=\"user_pass\" autocomplete=\"current-password\" spellcheck=\"false\" class=\"input\" value=\"\" size=\"20\" \/>\n\t\t\t<\/p><p class=\"login-remember\"><label><input name=\"rememberme\" type=\"checkbox\" id=\"rememberme\" value=\"forever\" \/> Se souvenir de moi<\/label><\/p><p class=\"login-submit\">\n\t\t\t\t<input type=\"submit\" name=\"wp-submit\" id=\"wp-submit\" class=\"button button-primary\" value=\"Se connecter\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"redirect_to\" value=\"https:\/\/kosovaideas.com\/fr\/wp-json\/wp\/v2\/product\/7248\" \/>\n\t\t\t<\/p><\/form><\/div><\/div>","wpcf_single_campaign":"\n<div class=\"wpneo-wrapper\">\n    <div class=\"wpneocf-container\">\n        <div id=\"primary\" class=\"content-area\">\n            <div id=\"content\" class=\"site-content\" role=\"main\">\n                <div class=\"wpneo-list-details\">\n\n\t\t\t\t\t                    <div itemscope itemtype=\"http:\/\/schema.org\/ItemList\" id=\"campaign-7248\" class=\"post-7248 product type-product status-publish has-post-thumbnail product_cat-arts-et-culture  instock sold-individually shipping-taxable purchasable product-type-crowdfunding\">\n\t\t\t\t\t\t<div class=\"wpneo-campaign-single-left-info\">\n    <div class=\"wpneo-post-img\">   \n        <a href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885.png\" itemprop=\"image\" class=\"wpneo-single-main-image zoom\" title=\"\" data-rel=\"prettyPhoto[product-gallery]\"><img width=\"730\" height=\"443\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885.png\" class=\"attachment-shop_single size-shop_single wp-post-image\" alt=\"\" title=\"1_664_885\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885.png 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885-300x182.png 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885-600x364.png 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a>        \n<div class=\"thumbnails\">\n\n<div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_166.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_166.jpg\"><img width=\"730\" height=\"486\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_166.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_166.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_166.jpg\" data-large_image_width=\"730\" data-large_image_height=\"486\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_166.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_166-300x200.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_166-600x399.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_178.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_178.jpg\"><img width=\"730\" height=\"483\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_178.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_178.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_178.jpg\" data-large_image_width=\"730\" data-large_image_height=\"483\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_178.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_178-300x198.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_178-600x397.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_219.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_219.jpg\"><img width=\"730\" height=\"483\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_219.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_219.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_219.jpg\" data-large_image_width=\"730\" data-large_image_height=\"483\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_219.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_219-300x198.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_219-600x397.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_272.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_272.jpg\"><img width=\"730\" height=\"425\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_272.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_272.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_272.jpg\" data-large_image_width=\"730\" data-large_image_height=\"425\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_272.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_272-300x175.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_272-600x349.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_292.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_292.jpg\"><img width=\"730\" height=\"486\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_292.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_292.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_292.jpg\" data-large_image_width=\"730\" data-large_image_height=\"486\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_292.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_292-300x200.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_292-600x399.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_297.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_297.jpg\"><img width=\"730\" height=\"486\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_297.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_297.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_297.jpg\" data-large_image_width=\"730\" data-large_image_height=\"486\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_297.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_297-300x200.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_297-600x399.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_298.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_298.jpg\"><img width=\"730\" height=\"486\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_298.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_298.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_298.jpg\" data-large_image_width=\"730\" data-large_image_height=\"486\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_298.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_298-300x200.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_298-600x399.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_301.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_301.jpg\"><img width=\"730\" height=\"486\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_301.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_301.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_301.jpg\" data-large_image_width=\"730\" data-large_image_height=\"486\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_301.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_301-300x200.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_301-600x399.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_375.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_375.jpg\"><img width=\"730\" height=\"401\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_375.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_375.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_375.jpg\" data-large_image_width=\"730\" data-large_image_height=\"401\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_375.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_375-300x165.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_375-600x330.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_440.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_440.jpg\"><img width=\"730\" height=\"486\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_440.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_440.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_440.jpg\" data-large_image_width=\"730\" data-large_image_height=\"486\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_440.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_440-300x200.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_440-600x399.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_447.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_447.jpg\"><img width=\"730\" height=\"483\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_447.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_447.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_447.jpg\" data-large_image_width=\"730\" data-large_image_height=\"483\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_447.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_447-300x198.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_447-600x397.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_470.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_470.jpg\"><img width=\"730\" height=\"483\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_470.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_470.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_470.jpg\" data-large_image_width=\"730\" data-large_image_height=\"483\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_470.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_470-300x198.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_470-600x397.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_472.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_472.jpg\"><img width=\"730\" height=\"336\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_472.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_472.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_472.jpg\" data-large_image_width=\"730\" data-large_image_height=\"336\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_472.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_472-300x138.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_472-600x276.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_506.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_506.jpg\"><img width=\"730\" height=\"410\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_506.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_506.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_506.jpg\" data-large_image_width=\"730\" data-large_image_height=\"410\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_506.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_506-300x168.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_506-600x337.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_510.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_510.jpg\"><img width=\"730\" height=\"337\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_510.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_510.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_510.jpg\" data-large_image_width=\"730\" data-large_image_height=\"337\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_510.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_510-300x138.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_510-600x277.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_529.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_529.jpg\"><img width=\"730\" height=\"486\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_529.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_529.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_529.jpg\" data-large_image_width=\"730\" data-large_image_height=\"486\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_529.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_529-300x200.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_529-600x399.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_530.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_530.jpg\"><img width=\"730\" height=\"483\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_530.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_530.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_530.jpg\" data-large_image_width=\"730\" data-large_image_height=\"483\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_530.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_530-300x198.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_530-600x397.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_565.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_565.jpg\"><img width=\"730\" height=\"486\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_565.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_565.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_565.jpg\" data-large_image_width=\"730\" data-large_image_height=\"486\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_565.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_565-300x200.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_565-600x399.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_600.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_600.jpg\"><img width=\"730\" height=\"335\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_600.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_600.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_600.jpg\" data-large_image_width=\"730\" data-large_image_height=\"335\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_600.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_600-300x138.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_600-600x275.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_629.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_629.jpg\"><img width=\"730\" height=\"486\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_629.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_629.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_629.jpg\" data-large_image_width=\"730\" data-large_image_height=\"486\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_629.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_629-300x200.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_629-600x399.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_641.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_641.jpg\"><img width=\"730\" height=\"336\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_641.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_641.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_641.jpg\" data-large_image_width=\"730\" data-large_image_height=\"336\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_641.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_641-300x138.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_641-600x276.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_655.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_655.jpg\"><img width=\"730\" height=\"486\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_655.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_655.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_655.jpg\" data-large_image_width=\"730\" data-large_image_height=\"486\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_655.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_655-300x200.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_655-600x399.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_666.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_666.jpg\"><img width=\"730\" height=\"483\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_666.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_666.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_666.jpg\" data-large_image_width=\"730\" data-large_image_height=\"483\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_666.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_666-300x198.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_666-600x397.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_672.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_672.jpg\"><img width=\"730\" height=\"486\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_672.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_672.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_672.jpg\" data-large_image_width=\"730\" data-large_image_height=\"486\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_672.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_672-300x200.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_672-600x399.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_708.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_708.jpg\"><img width=\"730\" height=\"486\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_708.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_708.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_708.jpg\" data-large_image_width=\"730\" data-large_image_height=\"486\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_708.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_708-300x200.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_708-600x399.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_751.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_751.jpg\"><img width=\"730\" height=\"337\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_751.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_751.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_751.jpg\" data-large_image_width=\"730\" data-large_image_height=\"337\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_751.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_751-300x138.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_751-600x277.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_773.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_773.jpg\"><img width=\"730\" height=\"486\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_773.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_773.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_773.jpg\" data-large_image_width=\"730\" data-large_image_height=\"486\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_773.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_773-300x200.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_773-600x399.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_778.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_778.jpg\"><img width=\"730\" height=\"337\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_778.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_778.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_778.jpg\" data-large_image_width=\"730\" data-large_image_height=\"337\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_778.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_778-300x138.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_778-600x277.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_780.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_780.jpg\"><img width=\"730\" height=\"486\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_780.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_780.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_780.jpg\" data-large_image_width=\"730\" data-large_image_height=\"486\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_780.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_780-300x200.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_780-600x399.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_781.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_781.jpg\"><img width=\"730\" height=\"336\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_781.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_781.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_781.jpg\" data-large_image_width=\"730\" data-large_image_height=\"336\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_781.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_781-300x138.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_781-600x276.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_787.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_787.jpg\"><img width=\"730\" height=\"483\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_787.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_787.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_787.jpg\" data-large_image_width=\"730\" data-large_image_height=\"483\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_787.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_787-300x198.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_787-600x397.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_809.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_809.jpg\"><img width=\"730\" height=\"486\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_809.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_809.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_809.jpg\" data-large_image_width=\"730\" data-large_image_height=\"486\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_809.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_809-300x200.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_809-600x399.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_813.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_813.jpg\"><img width=\"730\" height=\"486\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_813.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_813.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_813.jpg\" data-large_image_width=\"730\" data-large_image_height=\"486\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_813.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_813-300x200.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_813-600x399.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_875.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_875.jpg\"><img width=\"730\" height=\"486\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_875.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_875.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_875.jpg\" data-large_image_width=\"730\" data-large_image_height=\"486\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_875.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_875-300x200.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_875-600x399.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885-1.png\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885-1.png\"><img width=\"730\" height=\"443\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885-1.png\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885-1.png\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885-1.png\" data-large_image_width=\"730\" data-large_image_height=\"443\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885-1.png 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885-1-300x182.png 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885-1-600x364.png 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_888.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_888.jpg\"><img width=\"730\" height=\"486\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_888.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_888.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_888.jpg\" data-large_image_width=\"730\" data-large_image_height=\"486\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_888.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_888-300x200.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_888-600x399.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div><div data-thumb=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_916.jpg\" class=\"woocommerce-product-gallery__image\"><a itemprop=\"image\" class=\"woocommerce-main-image cloud-zoom\" href=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_916.jpg\"><img width=\"730\" height=\"410\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_916.jpg\" class=\"attachment-shop_single size-shop_single\" alt=\"\" title=\"\" data-src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_916.jpg\" data-large_image=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_916.jpg\" data-large_image_width=\"730\" data-large_image_height=\"410\" decoding=\"async\" srcset=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_916.jpg 730w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_916-300x168.jpg 300w, https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_916-600x337.jpg 600w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/a><\/div>\t<\/div>\n    <\/div>\n    \n    <div style=\"clear: both\"><\/div>\n<div class=\"wpneo-single-short-description\">\n    <h2>Court historique<\/h2>\n    <div itemprop=\"description\">\n        <div class=\"description\">MUSIC 4 ALL est une \u00e9cole de musique \u00e0 Plementina. Nous offrons des cours gratuits pour tous les enfants et les jeunes.<\/div>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n    <\/div>\n<\/div>\n<\/div>                        <div class=\"wpneo-campaign-summary\">\n                            <div class=\"wpneo-campaign-summary-inner\" itemscope itemtype=\"http:\/\/schema.org\/DonateAction\">\n\t\t\t\t\t\t\t\t<h2 class=\"wpneo-campaign-title\">MUSIC 4 ALL<\/h2><p class=\"wpneo-author-info\">\n    par    <a href=\"javascript:;\" data-author=\"1429\" class=\"wpneo-fund-modal-btn\">Xhemajl Jimmy Mustafa<\/a>\n<\/p><div class=\"woocommerce\"><\/div><div class=\"campaign-funding-info\">\n    <ul>\n        <li>\n            <p class=\"funding-amount\">\n                Non d\u00e9fini            <\/p>\n            <span class=\"info-text\">Objectif de financement<\/span>\n        <\/li>\n        <li>\n            <p class=\"funding-amount\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>&nbsp;5'075.00<\/bdi><\/span><\/p>\n            <span class=\"info-text\">Fonds recueillis<\/span>\n        <\/li>\n                    <li>\n                                    <p class=\"funding-amount\">0<\/p>\n                    <span class=\"info-text\">Jours restants<\/span>\n                            <\/li>\n        \n        <li>\n            <p class=\"funding-amount\">\n                Objectif cible            <\/p>\n            <span class=\"info-text\">M\u00e9thode de fin de campagne<\/span>\n        <\/li>\n    <\/ul>\n<\/div><div class=\"wpneo-raised-percent\">\n    <div class=\"wpneo-meta-name\">Pourcentage lev\u00e9 :<\/div>\n    <div class=\"wpneo-meta-desc\" >0%<\/div>\n<\/div>\n<div class=\"wpneo-raised-bar\">\n    <div id=\"neo-progressbar\">\n                <div style=\"width: 0%\"><\/div>\n    <\/div>\n<\/div><div class=\"wpneo-single-sidebar ASA\">\n\tLa campagne est r\u00e9ussie.<\/div><div class=\"wpneo-campaign-creator-info-wrapper\">\n    <div class=\"wpneo-campaign-creator-avatar\">\n                                    <img alt='' src='https:\/\/secure.gravatar.com\/avatar\/cd32dc0f30b1a2412b6e6badfa4c0ff5c859be0ce9b5d85503dfd16f5434ae55?s=80&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/cd32dc0f30b1a2412b6e6badfa4c0ff5c859be0ce9b5d85503dfd16f5434ae55?s=160&#038;d=mm&#038;r=g 2x' class='avatar avatar-80 photo' height='80' width='80' decoding='async'\/>                        <\/div>\n    <div class=\"wpneo-campaign-creator-details\">\n        <p><a href=\"javascript:;\" data-author=\"1429\" class=\"wpneo-fund-modal-btn\" >Xhemajl Jimmy Mustafa<\/a> <\/p>\n        <p>1 Campagnes | 0 Campagnes aim\u00e9es <\/p>\n                <p><a href=\"javascript:;\" data-author=\"1429\" class=\"wpneo-fund-modal-btn wpneo-link-style1\"><strong>Voir la bio compl\u00e8te.<\/strong><\/a><\/p>\n    <\/div>\n<\/div>                            <\/div><!-- .wpneo-campaign-summary-inner -->\n                        <\/div><!-- .wpneo-campaign-summary -->\n\t\t\t\t\t\t                                        <div class=\"social-container\">\n                <span>Partager\u00a0: <\/span>\n                <div class=\"links\">\n                                            <a href=\"javascript:void(0)\" class=\"wpcf-share s_facebook\"><i class=\"wpneo-icon wpneo-icon-facebook\"><\/i> <\/a>\n                                                                <a href=\"javascript:void(0)\" class=\"wpcf-share s_twitter\"><i class=\"wpneo-icon wpneo-icon-twitter\"><\/i> <\/a>\n                                                                                    <a href=\"javascript:void(0)\" class=\"wpcf-share s_linkedin\"><i class=\"wpneo-icon wpneo-icon-linkedin\"><\/i> <\/a>\n                                                                                                                                                                                                                                                    <a href=\"javascript:void(0)\" class=\"embedlink\" data-postid=\"https:\/\/kosovaideas.com\/fr\/product\/music-4-all\/\"><i class=\"wpneo-icon wpneo-icon-embed\" data-postid=\"7248\"><\/i><\/a>\n                                    <\/div>\n            <\/div>\n\n            <script type=\"text\/javascript\">\n                jQuery(document).ready(function($){\n                    $('.wpcf-share').ShareLink({\n                        title: \"MUSIC 4 ALL\",\n                        text: \"music-4-all-est-une-ecole-de-musique-a-plementina-nous-offrons-des-cours-gratuits-pour-tous-les-enfants-et-les-jeunes\",\n                        image: \"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/03\/1_664_885.png\",\n                        url: \"https:\/\/kosovaideas.com\/fr\/product\/music-4-all\/\"\n                    });\n                });\n            <\/script>\n                \n    \n    <div class=\"wpneo-tabs\">\n        <ul class=\"wpneo-tabs-menu\">\n                            <li class=\"wpneo-current description_tab\">\n                    <a href=\"#wpneo-tab-description\">Historique de la campagne<\/a>\n                <\/li>\n                    <\/ul>\n        <div class=\"wpneo-tab\">\n                            <div id=\"wpneo-tab-description\" class=\"wpneo-tab-content\">\n                    \n    <div class=\"tab-description tab_col_9 tab-campaign-story-left\">\n        <h2>Historique de la campagne<\/h2>\n        <p><strong>Qui sommes-nous?<\/strong><\/p>\n<p>Je m&rsquo;appelle Jimmy Mustafa et je fais partie d&rsquo;un groupe de musique Rom appel\u00e9 \u00ab\u00a0Jimmy Mustafa Band\u00a0\u00bb de Plementina. Plemetina est une petite ville de la municipalit\u00e9 d&rsquo;Obiliq, \u00e0 Prishtina. C&rsquo;est un lieu multiethnique o\u00f9 cohabitent Albanais, Serbes, Roms, Ashkali et autres. En 2009, six jeunes Roms ont uni leurs talents pour cr\u00e9er un genre diff\u00e9rent de musique traditionnelle rom et d&rsquo;autres styles de musique. Nous avons deux albums studio, le premier intitul\u00e9\u00a0<strong>\u00ab\u00a0Posvetime\u00a0\u00bb (D\u00e9di\u00e9<\/strong>) avec 10 titres et le second album \u00ab\u00a0<strong>Romane Bajrakja\u00a0\u00bb (Drapeaux Roms)<\/strong>\u00a0avec 11 chansons originales. En 2018 et 2019, le groupe a effectu\u00e9 une tourn\u00e9e en Suisse et en Allemagne.<\/p>\n<p>J&rsquo;ai \u00e9galement produit la musique de neuf films documentaires sur les Roms, tels que : Jek Kham Jek Sel, Naci Palem Khere, Sar Thuv, Live, Auschvic en Pologne, Roki, etc. J&rsquo;ai travaill\u00e9 avec des enfants en tant que professeur, leur apprenant \u00e0 jouer d&rsquo;instruments tels que la guitare, le cajon, le piano, et leur donnant des cours de chant. Je suis le fondateur d&rsquo;un centre pour les enfants et les jeunes, avec des amis du Kosovo et de la Suisse, appel\u00e9 Music 4 All.<\/p>\n<p><strong>Quel est notre objectif?<\/strong><\/p>\n<p>Notre centre \u00ab\u00a0Music 4 ALL\u00a0\u00bb sera une initiative pionni\u00e8re et des plus abouties qui permettra aux enfants et aux jeunes d&rsquo;\u00e9largir leurs activit\u00e9s musicales et artistiques et de se d\u00e9couvrir de nouveaux talents. Music 4 ALL \u00e9tait et restera un second foyer pour chaque enfant et chaque jeune. Tous ceux qui aiment l&rsquo;art de la musique et qui veulent apprendre ou am\u00e9liorer le chant et la pr\u00e9formation aux \u00e9tudes feront partie de ce projet.<\/p>\n<p>Music 4 ALL proposera des cours individuels et collectifs de musique classique et moderne tels que le piano, la clarinette, le cajon, la guitare, le chant, le sport, l&rsquo;enregistrement vid\u00e9o, le montage vid\u00e9o et d&rsquo;autres activit\u00e9s n\u00e9cessaires aux enfants et aux jeunes. Il y aura \u00e9galement une classe d&rsquo;art\/peinture o\u00f9 les enfants cr\u00e9eront de l&rsquo;art \u00e0 travers la musique avec notre aide.<\/p>\n<p>Nous aurons \u00e9galement des ateliers, o\u00f9 des artistes seront invit\u00e9s \u00e0 partager leurs exp\u00e9riences avec tout le monde. Nous enregistrerons de la musique (chansons\/albums) et organiserons \u00e9galement des concerts\/\u00e9v\u00e9nements, o\u00f9 tout le monde sera le bienvenu.<\/p>\n<p><strong>Comment votre soutien va-t-il nous aider?<\/strong><\/p>\n<p>Gr\u00e2ce \u00e0 votre soutien, nous donnerons aux enfants et aux jeunes de Plementina la possibilit\u00e9 de montrer leur talent en musique et en arts.<\/p>\n<p>Nous organiserons les activit\u00e9s suivantes :<\/p>\n<ul>\n<li>\u00c9ducation musicale<\/li>\n<li>Cours de piano<\/li>\n<li>Cours de clarinette<\/li>\n<li>Classes de chant\/voix<\/li>\n<li>Cours de guitare<\/li>\n<li>Cours de cajon<\/li>\n<li>Cours d&rsquo;informatique<\/li>\n<li>Cin\u00e9ma (diffusion de films)<\/li>\n<li>Cours de peinture<\/li>\n<\/ul>\n<p>Il y aura cinq cours proposant des ateliers de guitare, clarinette, piano, cajon et chant. Ces cours seront dispens\u00e9s afin d&rsquo;enrichir et d&rsquo;\u00e9tendre la partie pratique, permettant aux candidats d&rsquo;acqu\u00e9rir les notes et les comp\u00e9tences de base dans les instruments ainsi que le chant.<\/p>\n<p><strong>Budget<\/strong><\/p>\n<p>Total\u00a0\u20ac 5\u00a0000,00<\/p>\n<table width=\"509\">\n<tbody>\n<tr>\n<td width=\"29\">1)<\/td>\n<td width=\"388\">\u00a0Mat\u00e9riel p\u00e9dagogique<\/td>\n<td width=\"92\">\u00a0\u20ac 200,00<\/td>\n<\/tr>\n<tr>\n<td>2)<\/td>\n<td>\u00a0Mat\u00e9riel p\u00e9dagogique<\/td>\n<td>\u00a0\u20ac 120,00<\/td>\n<\/tr>\n<tr>\n<td>3)<\/td>\n<td>\u00a0Mat\u00e9riel artistique pour les enfants<\/td>\n<td>\u00a0\u20ac 150,00<\/td>\n<\/tr>\n<tr>\n<td>4)<\/td>\n<td>\u00a0Collations pour les enfants<\/td>\n<td>\u00a0\u20ac 500,00<\/td>\n<\/tr>\n<tr>\n<td>5)<\/td>\n<td>\u00a0Transport hebdomadaire de Plementina \u00e0 Obiliq et Prishtina<\/td>\n<td>\u00a0\u20ac 600,00<\/td>\n<\/tr>\n<tr>\n<td>6)<\/td>\n<td>\u00a0PC pour le montage<\/td>\n<td>\u00a0\u20ac 800,00<\/td>\n<\/tr>\n<tr>\n<td>7)<\/td>\n<td>\u00a0Appareil photo<\/td>\n<td>\u00a0\u20ac 750,00<\/td>\n<\/tr>\n<tr>\n<td>8)<\/td>\n<td>\u00a0\u00c9v\u00e9nements suppl\u00e9mentaires, concerts<\/td>\n<td>\u00a0\u20ac 880,00<\/td>\n<\/tr>\n<tr>\n<td>9)<\/td>\n<td>\u00a0Chauffage<\/td>\n<td>\u00a0\u20ac 500,00<\/td>\n<\/tr>\n<tr>\n<td>10)<\/td>\n<td>\u00a010% de frais de carte de cr\u00e9dit, de virement bancaire et de plateforme<\/td>\n<td>\u00a0\u20ac 500,00<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n    <\/div>\n\n<div class=\"tab-rewards tab_col_3 tab-campaign-story-right\">\n    <div style=\"clear: both\"><\/div>\t<div style=\"clear: both\"><\/div>\n<\/div>                <\/div>\n                    <\/div>\n        <div class=\"clear-float\"><\/div>\n    <\/div>\n\n                        <meta itemprop=\"url\" content=\"https:\/\/kosovaideas.com\/fr\/product\/music-4-all\/\" \/>\n                    <\/div><!-- #campaign-7248 -->\n\t\t\t\t\t\t\t\t\t\t\n                <\/div>\n            <\/div><!-- #content -->\n        <\/div><!-- #primary -->\n    <\/div>\n\n<\/div>\n","wpcf_popular_campaign":[{"ID":14771,"post_author":"1518","post_date":"2024-09-23 11:27:57","post_date_gmt":"2024-09-23 10:27:57","post_content":"Le programme du matin sur Radio T\u00e9l\u00e9vision du Kosovo lance une nouvelle campagne de collecte de fonds visant \u00e0 cr\u00e9er des espaces r\u00e9cr\u00e9atifs dans les \u00e9coles primaires des zones rurales du Kosovo. Cette initiative, appel\u00e9e \"Apprendre et Jouer\", cherche \u00e0 transformer les environnements scolaires en espaces attrayants pour l'apprentissage et le jeu, offrant ainsi plus d'opportunit\u00e9s aux \u00e9l\u00e8ves de se d\u00e9velopper \u00e0 la fois sur le plan \u00e9ducatif et social.\r\n\r\nAvec votre participation, nous vous invitons \u00e0 contribuer financi\u00e8rement pour s\u00e9curiser le mat\u00e9riel n\u00e9cessaire et aider \u00e0 cr\u00e9er des espaces r\u00e9cr\u00e9atifs qui am\u00e9lioreront l'exp\u00e9rience scolaire des \u00e9l\u00e8ves du primaire. Chaque contribution est r\u00e9alis\u00e9e \u00e0 travers un processus enti\u00e8rement transparent, o\u00f9 chaque don aura un impact direct sur la cr\u00e9ation de ces espaces.\r\n\r\n<strong>Pourquoi \"Apprendre et Jouer\" ?<\/strong>\r\n\r\nLes espaces r\u00e9cr\u00e9atifs sont essentiels pour cr\u00e9er un environnement plus engageant et motivant pour les enfants, surtout dans les zones rurales. Ces lieux ne sont pas seulement des espaces de jeu \u2013 ils offrent des opportunit\u00e9s de stimulation, de d\u00e9veloppement des comp\u00e9tences sociales, et encouragent une plus grande implication scolaire. Ces espaces sont con\u00e7us pour offrir un \u00e9quilibre sain entre l'apprentissage et le jeu, renfor\u00e7ant ainsi le lien des \u00e9l\u00e8ves avec l'\u00e9cole et aidant \u00e0 pr\u00e9venir l'abandon scolaire.\r\n\r\n<strong>Que proposent ces espaces ?<\/strong>\r\n<ul>\r\n \t<li>Des zones con\u00e7ues pour diverses activit\u00e9s, y compris la lecture, les arts et les jeux.<\/li>\r\n \t<li>Des jeux et des activit\u00e9s physiques, comme le ping-pong, pour promouvoir \u00e0 la fois la sant\u00e9 physique et mentale.<\/li>\r\n \t<li>Des coins collaboratifs et de d\u00e9veloppement social, o\u00f9 les enfants peuvent apprendre en jouant en groupe, renfor\u00e7ant ainsi leurs comp\u00e9tences en communication et en interaction sociale.<\/li>\r\n \t<li>Des mini-biblioth\u00e8ques et des coins de lecture, encourageant les \u00e9l\u00e8ves \u00e0 explorer le monde \u00e0 travers les livres et \u00e0 cultiver un amour pour la connaissance.<\/li>\r\n \t<li>Des espaces color\u00e9s et vibrants avec des murs d\u00e9cor\u00e9s, cr\u00e9ant une atmosph\u00e8re chaleureuse et motivante pour les enfants.<\/li>\r\n<\/ul>\r\nEn fonction des fonds r\u00e9colt\u00e9s, nous visons \u00e0 fournir \u00e0 chaque \u00e9cole :\r\n<ul>\r\n \t<li>Une table de ping-pong<\/li>\r\n \t<li>Un coin lecture avec des coussins confortables<\/li>\r\n \t<li>Un coin mini-biblioth\u00e8que<\/li>\r\n \t<li>La d\u00e9coration et la peinture des espaces pour cr\u00e9er une ambiance anim\u00e9e et accueillante<\/li>\r\n<\/ul>\r\nLe montant requis est de <strong>3,300 \u20ac<\/strong>, ce qui inclut une commission administrative de 10 % sur la plateforme KOSOVAideas.\r\n\r\n<strong>Comment pouvez-vous contribuer ?<\/strong>\r\n\r\nVotre contribution peut faire une diff\u00e9rence significative dans la vie des enfants des zones rurales du Kosovo. Chaque aide, m\u00eame minime, contribuera \u00e0 b\u00e2tir un avenir meilleur pour les jeunes g\u00e9n\u00e9rations. Rejoignez-nous et faites partie de cette initiative pour cr\u00e9er un environnement plus heureux, plus sain et plus motivant pour nos \u00e9l\u00e8ves.\r\n\r\n<strong>Project Team<\/strong>\r\n\r\n<img class=\"alignnone wp-image-14738 size-thumbnail\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/09\/Trendelina-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>\u00a0 \u00a0 \u00a0 <img class=\"alignnone wp-image-14742 size-thumbnail\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/09\/Valtona-rotated-e1727077479833.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>\u00a0 \u00a0 \u00a0 <img class=\"alignnone wp-image-14733 size-thumbnail\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/09\/RTK-Llogo-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>\r\n\r\n<strong>Tr\u00ebndelin\u00eb Bucolli\u00a0 \u00a0 \u00a0Valtona Kelmendi\u00a0 \u00a0 \u00a0Radio management<\/strong>\r\n\r\nAuthor Host\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Author Host","post_title":"\"Learn and Play\" \u2013 Cr\u00e9er des espaces r\u00e9cr\u00e9atifs pour les enfants du Kosovo","post_excerpt":"La campagne \"Learn and Play\" de Radio T\u00e9l\u00e9vision du Kosovo cr\u00e9e des espaces r\u00e9cr\u00e9atifs dans les \u00e9coles rurales. Votre soutien fournit des \u00e9quipements essentiels pour am\u00e9liorer l'apprentissage et le jeu des \u00e9l\u00e8ves. Rejoignez-nous pour faire la diff\u00e9rence !","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"learn-and-play-creer-des-espaces-recreatifs-pour-les-enfants-du-kosovo","to_ping":"","pinged":"","post_modified":"2024-09-23 12:50:02","post_modified_gmt":"2024-09-23 11:50:02","post_content_filtered":"","post_parent":0,"guid":"https:\/\/kosovaideas.com\/?post_type=product&#038;p=14771","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":14410,"post_author":"1515","post_date":"2024-08-15 07:33:26","post_date_gmt":"2024-08-15 06:33:26","post_content":"<div class=\"flex max-w-full flex-col flex-grow\">\r\n<div class=\"min-h-[20px] text-message flex w-full flex-col items-end gap-2 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"3a17d53c-4b09-4f9c-ac94-3f3d313a2858\">\r\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\r\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\r\n\r\n<strong>POURQUOI PRISHTINA A-T-ELLE BESOIN D'UN CIN\u00c9MA ET D'UN TH\u00c9\u00c2TRE EN PLEIN AIR POUR LES JEUNES DE PLUS DE 10 ANS ?<\/strong> Prishtina, la capitale du Kosovo avec une population diversifi\u00e9e et dynamique, poss\u00e8de un riche patrimoine culturel. Cependant, la ville manque d'une plateforme d\u00e9di\u00e9e o\u00f9 les jeunes peuvent explorer et exprimer leurs talents dans le cin\u00e9ma et le th\u00e9\u00e2tre. Bien que des \u00e9v\u00e9nements occasionnels soient organis\u00e9s, il existe un besoin pour un espace structur\u00e9 et durable o\u00f9 les jeunes esprits peuvent r\u00e9guli\u00e8rement s'engager dans les arts du spectacle. Malgr\u00e9 ce manque, l'int\u00e9r\u00eat et le talent parmi les jeunes de Prishtina ne manquent pas. Ce qui manque, c'est un environnement favorable o\u00f9 ces jeunes individus peuvent canaliser leur cr\u00e9ativit\u00e9 et leur passion pour les arts. Actuellement, les options de divertissement et de socialisation pour les jeunes se limitent aux caf\u00e9s et restaurants.\r\n\r\n<strong>QUEL EST NOTRE OBJECTIF ?<\/strong> Le Cin\u00e9ma et Th\u00e9\u00e2tre en Plein Air de Prishtina vise \u00e0 cr\u00e9er un espace culturel informel o\u00f9 les jeunes de 10 ans et plus peuvent s'immerger dans le monde du cin\u00e9ma et du th\u00e9\u00e2tre. Nos objectifs sont les suivants :\r\n<ol>\r\n \t<li><strong>\u00c9ducation et exposition culturelle :<\/strong>\r\n<ul>\r\n \t<li><strong>Projections de films et de documentaires :<\/strong> Organiser r\u00e9guli\u00e8rement des projections de films classiques et contemporains pour \u00e9largir les horizons culturels et encourager l'appr\u00e9ciation de diff\u00e9rents styles et genres cin\u00e9matographiques.<\/li>\r\n \t<li><strong>Organisation de performances musicales et th\u00e9\u00e2trales :<\/strong> Offrir des plateformes pour des performances en direct, encourageant les jeunes \u00e0 s'engager dans des productions musicales et th\u00e9\u00e2trales, am\u00e9liorant ainsi leurs comp\u00e9tences artistiques.<\/li>\r\n \t<li><strong>Organisation d'\u00e9v\u00e9nements litt\u00e9raires et artistiques :<\/strong> Promouvoir l'expression litt\u00e9raire et artistique \u00e0 travers des lectures de po\u00e9sie, des clubs de lecture, des expositions d'art et des ateliers de dessin.<\/li>\r\n<\/ul>\r\n<\/li>\r\n \t<li><strong>D\u00e9veloppement des comp\u00e9tences et expression :<\/strong>\r\n<ul>\r\n \t<li><strong>Soutien aux jeunes artistes :<\/strong> Offrir des opportunit\u00e9s aux jeunes artistes dans le cin\u00e9ma, la musique, les arts et d'autres disciplines pour montrer leurs talents.<\/li>\r\n \t<li><strong>Organisation d'ateliers et de cours :<\/strong> Faciliter des ateliers \u00e9ducatifs et des cours sur divers aspects de la production cin\u00e9matographique et th\u00e9\u00e2trale, y compris le jeu d'acteur, la r\u00e9alisation, l'\u00e9criture de sc\u00e9narios, la sc\u00e9nographie et la production technique.<\/li>\r\n<\/ul>\r\n<\/li>\r\n \t<li><strong>Durabilit\u00e9 \u00e0 long terme :<\/strong>\r\n<ul>\r\n \t<li><strong>D\u00e9veloppement d'un plan triennal :<\/strong> Cr\u00e9er un plan durable pour assurer la long\u00e9vit\u00e9 du club et sa contribution continue \u00e0 la sc\u00e8ne culturelle de Prishtina. Cela inclut la s\u00e9curisation d'un financement \u00e0 long terme, l'\u00e9tablissement de partenariats et la mise en \u0153uvre de strat\u00e9gies de gestion efficaces.<\/li>\r\n<\/ul>\r\n<\/li>\r\n \t<li><strong>Engagement communautaire et impact social :<\/strong>\r\n<ul>\r\n \t<li><strong>Promotion de l'inclusivit\u00e9 :<\/strong> Cr\u00e9er un environnement inclusif o\u00f9 tous les jeunes, quel que soit leur milieu socio-\u00e9conomique, peuvent participer et b\u00e9n\u00e9ficier des activit\u00e9s du club.<\/li>\r\n \t<li><strong>Am\u00e9lioration des comp\u00e9tences sociales :<\/strong> \u00c0 travers des projets collaboratifs et des activit\u00e9s de groupe, aider les participants \u00e0 d\u00e9velopper des comp\u00e9tences sociales essentielles telles que le travail d'\u00e9quipe, la communication et le leadership.<\/li>\r\n \t<li><strong>Renforcement des liens communautaires :<\/strong> Engager la communaut\u00e9 au sens large en invitant les familles et les r\u00e9sidents \u00e0 assister aux performances et spectacles, renfor\u00e7ant ainsi un sentiment de communaut\u00e9 et d'identit\u00e9 culturelle partag\u00e9e.<\/li>\r\n<\/ul>\r\n<\/li>\r\n \t<li><strong>D\u00e9veloppement personnel et autonomisation :<\/strong>\r\n<ul>\r\n \t<li><strong>Renforcement de la confiance en soi :<\/strong> Fournir un environnement de soutien o\u00f9 les jeunes peuvent renforcer leur confiance en eux gr\u00e2ce \u00e0 la performance et \u00e0 l'expression cr\u00e9ative.<\/li>\r\n \t<li><strong>Encouragement de la pens\u00e9e critique :<\/strong> \u00c0 travers des discussions et des analyses de films et de performances, encourager les participants \u00e0 penser de mani\u00e8re critique et \u00e0 d\u00e9velopper leurs propres perspectives sur diverses questions culturelles et sociales.<\/li>\r\n \t<li><strong>Promotion du bien-\u00eatre \u00e9motionnel :<\/strong> Offrir un espace s\u00fbr o\u00f9 les jeunes peuvent exprimer leurs sentiments et pens\u00e9es de mani\u00e8re cr\u00e9ative, contribuant \u00e0 leur bien-\u00eatre mental et \u00e9motionnel global.<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ol>\r\nEn cr\u00e9ant ce club, nous visons \u00e0 dynamiser la sc\u00e8ne culturelle de Prishtina et \u00e0 am\u00e9liorer la vie sociale de nos citoyens, en particulier les jeunes. Nous pr\u00e9voyons de collaborer avec diverses organisations pour assurer l'inclusivit\u00e9 et offrir un acc\u00e8s gratuit ou subventionn\u00e9 \u00e0 ceux qui en ont besoin.\r\n\r\n<strong>QUI SOMMES-NOUS ?<\/strong>\r\n\r\nLe Centre Culturel pour Enfants (QKF) de Prishtina a \u00e9t\u00e9 \u00e9tabli le 19 novembre 1961. La vision du Centre Culturel pour Enfants est de cr\u00e9er des exp\u00e9riences artistiques diversifi\u00e9es pour cultiver l'amour des arts, aidant les jeunes groupes d'\u00e2ge \u00e0 faire de l'art, de la musique et de la danse une partie de leur vie. Le Centre Culturel pour Enfants de Prishtina m\u00e8ne ses activit\u00e9s dans les locaux du \"Palais de la Jeunesse\" \u00e0 travers l'organisation de divers secteurs tels que la musique, le groupe litt\u00e9raire, le groupe de danse, le groupe de th\u00e9\u00e2tre et le club des jeunes ambassadeurs. Au sein de ce centre, les enfants \u00e2g\u00e9s de 6 \u00e0 16 ans sont admis et engag\u00e9s en fonction de leur volont\u00e9, de leurs comp\u00e9tences et de leur talent. Les enfants, \u00e0 travers leurs activit\u00e9s dans divers secteurs, participent souvent \u00e0 des \u00e9v\u00e9nements tant sur le plan national qu'international, tels que des festivals et diverses comp\u00e9titions. Ces participations ont abouti \u00e0 de nombreux dipl\u00f4mes et diff\u00e9rentes reconnaissances. Les r\u00e9alisations qui distinguent et soulignent le Centre Culturel pour Enfants sont les diverses personnalit\u00e9s dans la vie publique et artistique qui ont fait partie du QKF dans diff\u00e9rents secteurs.\r\n\r\n<strong>DE QUOI AVONS-NOUS BESOIN ?<\/strong>\r\n\r\nPour concr\u00e9tiser cette vision, nous avons besoin de votre soutien pour financer :\r\n\r\n\u2022 Projecteur vid\u00e9o de qualit\u00e9 pour les espaces ouverts, \u00e9quipement audio et \u00e9quipement technologique suppl\u00e9mentaire \u2013 3 000 \u20ac\r\n\r\n\u2022 G\u00e9n\u00e9rateur, c\u00e2bles et \u00e9quipement d'\u00e9clairage \u2013 1 500 \u20ac\r\n\r\n\u2022 Mat\u00e9riel de soutien tel que des chaises, des tapis et des nattes \u2013 1 300 \u20ac\r\n\r\n\u2022 Frais de programme (location de films et organisation de performances) \u2013 1 550 \u20ac\r\n\r\n\u2022 Logistique de soutien \u2013 2 000 \u20ac \u2022\r\n\r\nFrais d'administration de 10 % sur KOSOVAideas\r\n\r\nTotal :<strong> 10 390 \u20ac<\/strong>\r\n\r\n<strong>COMMENT VOTRE SOUTIEN AIDERA-T-IL EXACTEMENT ?<\/strong> Vos dons nous aideront \u00e0 acqu\u00e9rir l'\u00e9quipement technique n\u00e9cessaire et \u00e0 cr\u00e9er un espace confortable et accueillant pour nos membres. En finan\u00e7ant cette initiative, vous contribuerez \u00e0 l'enrichissement culturel de la jeunesse de Prishtina, en leur offrant des opportunit\u00e9s de d\u00e9velopper leurs comp\u00e9tences, d'exprimer leur cr\u00e9ativit\u00e9 et de s'engager dans l'art et la culture.\r\n\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"mt-1 flex gap-3 empty:hidden -ml-2\">\r\n<div class=\"items-center justify-start rounded-xl p-1 flex\">\r\n<div class=\"flex items-center\"><strong>PROJECT TEAM<\/strong><\/div>\r\n<\/div>\r\n<\/div>\r\n<img class=\"alignnone wp-image-14397\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/08\/Ariana-1-300x260.jpg\" alt=\"\" width=\"187\" height=\"162\" \/>\u00a0 \u00a0 <img class=\"alignnone wp-image-14401\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/08\/Foto-247x300.jpg\" alt=\"\" width=\"137\" height=\"166\" \/>\u00a0 \u00a0 <img class=\"alignnone wp-image-14405\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/08\/Muhamet-Jashanica-300x300.jpg\" alt=\"\" width=\"166\" height=\"166\" \/> <img class=\"alignnone wp-image-14457\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/08\/Jetlira-300x200.jpg\" alt=\"\" width=\"250\" height=\"166\" \/> <img class=\"alignnone wp-image-14461\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/08\/Gentrit-Zogejani-240x300.jpg\" alt=\"\" width=\"167\" height=\"209\" \/>\r\n\r\n<strong>Ariana Kasapolli\u00a0 \u00a0<\/strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <strong>Albana Isufi<\/strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<strong>Muhamet Jashanica\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Jetlira Ademi\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Gentrit Zogejani<\/strong>\r\n\r\n&nbsp;","post_title":"Inspirez la jeunesse de Prishtina : Lib\u00e9rez la cr\u00e9ativit\u00e9 \u00e0 travers le cin\u00e9ma et le th\u00e9\u00e2tre en plein air","post_excerpt":"Alimentez les r\u00eaves de la jeunesse de Prishtina\u2014aidez-les \u00e0 explorer, s'exprimer et s'\u00e9panouir gr\u00e2ce au cin\u00e9ma et au th\u00e9\u00e2tre en plein air.","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"inspirez-la-jeunesse-de-prishtina-liberez-la-creativite-a-travers-le-cinema-et-le-theatre-en-plein-air","to_ping":"","pinged":"","post_modified":"2024-08-15 07:36:48","post_modified_gmt":"2024-08-15 06:36:48","post_content_filtered":"","post_parent":0,"guid":"https:\/\/kosovaideas.com\/?post_type=product&#038;p=14410","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":13053,"post_author":"10","post_date":"2024-03-26 15:08:13","post_date_gmt":"2024-03-26 14:08:13","post_content":"<strong>Qui sommes nous?<\/strong>\r\n\r\nLa Fondation IPKO (IF) n\u2019est pas seulement une fondation ; nous sommes des catalyseurs de changement. Notre mission fait \u00e9cho aux r\u00eaves d\u2019innombrables filles \u00e0 travers le Kosovo. Depuis 25 ans, IF se consacre \u00e0 former les futurs dirigeants du Kosovo qui exploiteront la puissance de la technologie pour relever de front les d\u00e9fis locaux et nationaux.\r\n\r\nNous avons soutenu des dizaines de milliers de filles \u00e0 travers nos programmes, notamment Girls in ICT, Women in Cyber, WikiAcademy, AI Kosovo, pour qu'elles acqui\u00e8rent des connaissances, acqui\u00e8rent de nouvelles comp\u00e9tences et r\u00e9alisent leurs r\u00eaves. Notre vision s'\u00e9tend au-del\u00e0 de l'horizon, o\u00f9 chaque fille peut s'\u00e9panouir dans un environnement favorable, atteignant son plein potentiel dans un paysage de progr\u00e8s et d'opportunit\u00e9s.\r\n\r\n<strong>Quel est notre objectif ?<\/strong>\r\n\r\nDonnez-lui du pouvoir\u00a0! constitue une lueur d\u2019espoir pour les filles issues de milieux ruraux et marginalis\u00e9s. Nous avons pour mission de briser les barri\u00e8res et d\u2019ouvrir les portes aux opportunit\u00e9s. Gr\u00e2ce \u00e0 des cours STEM de haute qualit\u00e9 et au mentorat de femmes qui r\u00e9ussissent, nous ouvrons la voie \u00e0 plus de 100 000 filles du Kosovo \u00e2g\u00e9es de 11 \u00e0 18 ans pour qu'elles deviennent les leaders et les actrices du changement de demain. Il ne s'agit pas seulement d'\u00e9ducation; il s'agit d'autonomisation, d'\u00e9galit\u00e9 et de transformation des vies.\r\n\r\n<strong>De quoi avons nous besoin?<\/strong>\r\n\r\nPour transformer notre vision en r\u00e9alit\u00e9, nous avons besoin de votre soutien. Vos contributions financeront des bourses d'\u00e9tudes pour 150 filles m\u00e9ritantes, leur offrant ainsi un acc\u00e8s \u00e0 l'\u00e9ducation, \u00e0 des ressources et \u00e0 des opportunit\u00e9s auparavant inaccessibles. Ces bourses couvriront les frais de scolarit\u00e9, le mat\u00e9riel p\u00e9dagogique et les ressources technologiques. Ensemble, nous pouvons garantir que chaque fille dispose des outils dont elle a besoin pour exceller dans les domaines STEM et au-del\u00e0.\r\n\r\n<strong>Budget<\/strong>\r\n<ul>\r\n \t<li>15 000 \u00e0 150 bourses (80 \u00e0 100 euros par bourse)<\/li>\r\n \t<li>1 000 - Publicit\u00e9 et promotion<\/li>\r\n \t<li>2 000 - Transport<\/li>\r\n \t<li>10\u00a0% pour la plateforme Kosovo Ideas<\/li>\r\n<\/ul>\r\nTotal = 20 000\r\n\r\n<strong>Objectif \u00e9tendu 1<\/strong>\r\n<ul>\r\n \t<li>8 000 - 100 bourses suppl\u00e9mentaires<\/li>\r\n \t<li>4\u00a0000\u00a0\u2013\u00a0Support \u00e9tendu pour les cours de niveau sup\u00e9rieur destin\u00e9s aux 50\u00a0filles les plus performantes<\/li>\r\n \t<li>2 000 - Journ\u00e9e des filles dans les TIC \u2013 mentorat, universit\u00e9 et salon de l'emploi<\/li>\r\n \t<li>1 400 - 10\u00a0% pour la plateforme KosovoIdeas<\/li>\r\n<\/ul>\r\nTotal = 15 000\r\n\r\n<strong>Comment le support nous aidera-t-il ?<\/strong>\r\n\r\nVotre don nous permettra de recruter des prestataires de formation locaux de haute qualit\u00e9 pour proposer une gamme de cours technologiques inspirants et r\u00e9pondant aux normes internationales \u00e0 150 filles de tout le Kosovo. Les offres de cours, propos\u00e9es \u00e0 prix r\u00e9duit par nos partenaires, seront accessibles aux filles de leurs communaut\u00e9s et enseign\u00e9es \u00e0 un niveau appropri\u00e9 \u00e0 leur \u00e2ge, leur exp\u00e9rience et leurs int\u00e9r\u00eats. Les filles qui excellent et se montrent prometteuses seront soutenues pour poursuivre des cours avanc\u00e9s.\r\n\r\n<strong><em>Votre soutien \u00e0 EmpowerHer\u00a0! n'est pas seulement un don ; c'est un catalyseur de changement.<\/em><\/strong>\r\n\r\nAvec votre aide, nous donnerons aux filles les moyens de poursuivre leurs passions, de surmonter les barri\u00e8res et de devenir des leaders dans leurs communaut\u00e9s. Ensemble, nous m\u00e8nerons un changement syst\u00e9mique, remettrons en question les st\u00e9r\u00e9otypes, plaiderons pour l'\u00e9galit\u00e9 et favoriserons une culture d'inclusion et d'autonomisation. Votre investissement ne se limite pas \u00e0 leur avenir\u00a0; c'est un investissement dans un monde plus brillant et plus inclusif pour nous tous.\r\n\r\n<strong>Message sp\u00e9cial\u00a0:<\/strong>\r\n\r\nCe mois-ci, nous vous invitons \u00e0 oublier votre caf\u00e9 quotidien et \u00e0 investir dans quelque chose de vraiment extraordinaire : les r\u00eaves des jeunes femmes en herbe. Un mois de sacrifice peut soutenir deux filles et leurs r\u00eaves technologiques. Ensemble, nous transformerons de petits choix en grandes opportunit\u00e9s, cr\u00e9ant ainsi un effet d'entra\u00eenement d'autonomisation et d'opportunit\u00e9s au Kosovo et au-del\u00e0.\r\n\r\n&nbsp;\r\n\r\n<strong>Project Team<\/strong>\r\n\r\n&nbsp;\r\n\r\n<img class=\"\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Teresa-Crawford.jpg\" width=\"115\" height=\"153\" \/>\u00a0 \u00a0 \u00a0<strong><img class=\"alignnone  wp-image-13234\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Kushtrim-Xhakli.jpg\" alt=\"\" width=\"123\" height=\"154\" \/>\u00a0 \u00a0 <img class=\"alignnone wp-image-13062\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Abetare-Gojani-Executive-Director.png\" alt=\"\" width=\"149\" height=\"153\" \/><\/strong>\u00a0 <img class=\"alignnone  wp-image-13258\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Adelina-Qarri-Senior-Program-Manager-1.png\" alt=\"\" width=\"148\" height=\"152\" \/>\u00a0 \u00a0 \u00a0\u00a0<img class=\"alignnone wp-image-13070\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Arbresha-Tuhina-Finance-Manager.png\" alt=\"\" width=\"149\" height=\"153\" \/>\u00a0 \u00a0<img class=\"alignnone wp-image-13078\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Dina-Spahija-Program-Manager.png\" alt=\"\" width=\"159\" height=\"160\" \/>\r\n\r\nTeresa Crawford\u00a0 \u00a0 \u00a0Kushtrim Xhakli\u00a0 \u00a0 \u00a0Abetare Gojani\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Adelina Qarri\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Arbresha Tuhina\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Dina Spahija\r\n\r\n<img class=\"alignnone wp-image-13082\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Miranada-Vula-Admin-and-Finance-Associate.png\" alt=\"\" width=\"141\" height=\"144\" \/> <img class=\"alignnone wp-image-13086\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Vlora-Shabiu-Program-Manager.png\" alt=\"\" width=\"146\" height=\"146\" \/> <strong><img class=\"alignnone  wp-image-13238\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Miranda-Korpuzi-scaled.jpg\" alt=\"\" width=\"217\" height=\"144\" \/> <img class=\"alignnone  wp-image-13242\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Adriatik-Llugiqi-scaled.jpg\" alt=\"\" width=\"216\" height=\"144\" \/> <img class=\"alignnone  wp-image-13250\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Loreta-Zharjani-scaled.jpg\" alt=\"\" width=\"217\" height=\"144\" \/><\/strong>\r\n\r\nMiranda Vula\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Vlora Shabiu\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Miranda Korpuzi\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Adriatik Llugiqi\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Loreta Zharjani\r\n\r\n<strong> <img class=\"alignnone  wp-image-13246\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Jetmire-Maloku.jpg\" alt=\"\" width=\"132\" height=\"132\" \/>\u00a0 \u00a0 \u00a0<\/strong>\r\n\r\nJetmire Maloku","post_title":"EmpowerHer!","post_excerpt":"EmpowerHer! Les bourses alimentent les r\u00eaves technologiques des filles au Kosovo, cr\u00e9ant une onde de renforcement et d'\u00e9galit\u00e9 des sexes dans les STEM.\r\n<div class=\"flex-1 overflow-hidden\">\r\n<div class=\"react-scroll-to-bottom--css-qlehz-79elbk h-full\">\r\n<div class=\"react-scroll-to-bottom--css-qlehz-1n7m0yu\">\r\n<div class=\"flex flex-col text-sm pb-9\">\r\n<div class=\"w-full text-token-text-primary\" data-testid=\"conversation-turn-5\">\r\n<div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\">\r\n<div class=\"flex flex-1 text-base mx-auto gap-3 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] group final-completion\">\r\n<div class=\"relative flex w-full flex-col agent-turn\">\r\n<div class=\"flex-col gap-1 md:gap-3\">\r\n<div class=\"mt-1 flex justify-start gap-3 empty:hidden\">\r\n<div class=\"text-gray-400 flex self-end lg:self-center items-center justify-center lg:justify-start mt-0 -ml-1 h-7 gap-[2px] visible\">\r\n<div class=\"flex\"><\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"pr-2 lg:pr-0\"><\/div>\r\n<\/div>\r\n<div class=\"absolute\">\r\n<div class=\"flex w-full gap-2 items-center justify-center\"><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"w-full pt-2 md:pt-0 dark:border-white\/20 md:border-transparent md:dark:border-transparent md:w-[calc(100%-.5rem)]\"><form class=\"stretch mx-2 flex flex-row gap-3 last:mb-2 md:mx-4 md:last:mb-6 lg:mx-auto lg:max-w-2xl xl:max-w-3xl\">\r\n<div class=\"relative flex h-full flex-1 flex-col\">\r\n<div class=\"absolute bottom-full left-0 right-0\"><\/div>\r\n<div class=\"flex w-full items-center\"><\/div>\r\n<\/div>\r\n<\/form><\/div>","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"empowerher","to_ping":"","pinged":"","post_modified":"2024-03-27 15:06:06","post_modified_gmt":"2024-03-27 14:06:06","post_content_filtered":"","post_parent":0,"guid":"https:\/\/kosovaideas.com\/?post_type=product&#038;p=13053","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":12895,"post_author":"1499","post_date":"2024-03-19 08:34:48","post_date_gmt":"2024-03-19 07:34:48","post_content":"<strong>Who we are?<\/strong>\r\n\r\nThe organization Kosovo Institute of Logopedics was founded in 2018 and has as its mission the promotion of speech therapy services in the educational facilities of Kosovo, aiming to ensure that every child has access to the treatment and assistance necessary for the development of communication skills. The organization is led by speech therapist Mrs. Ardita Uka-Rexha. We believe that every child has the right to a quality education and specialist support to reach their full potential. The Kosovo Institute of Logopedics counts 30+ projects, 258+ volunteers and currently the main projects are the installation of communication signs in parks in Kosovo and the provision of free speech therapy services in regular schools.\r\n\r\n<strong>What is our purpose?<\/strong>\r\n\r\nOur goal is to raise a fund of 4,400 EUR to continue and expand our speech therapy services in our community. Funds raised will be used to ensure the training of our staff, the improvement of our speech therapy cabinets and to provide necessary materials for the evaluation and treatment of children.\r\n\r\n<strong>What do we need?<\/strong>\r\n\r\nTo achieve our goal, we ask for your financial support to ensure that our speech therapy services are accessible to all children with articulation difficulties. Your help will help build an environment dedicated to the development of our children's communication skills and increase awareness of the importance of speech therapy in their education.\r\n\r\nPlease join us in this important mission to help our children communicate and help shape a society more aware of their needs.\r\n\r\n<em><strong>Thank you for your endless support!<\/strong><\/em>\r\n\r\n<strong>Budget for the Project<\/strong>\r\n\r\nSpecific assessment materials from Turn &amp; Talk\u00ae (superduperinc.com) \u20ac1,500\r\n\r\nSpeech therapy materials \u20ac2,000\r\n\r\nTransportation of volunteers \u20ac500\r\n\r\nFee 10% KOSOVAideas\r\n\r\n<strong>Total \u20ac4,440<\/strong>\r\n\r\n<strong>Project Team<\/strong>\r\n\r\n<img class=\"alignnone wp-image-12896\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Ardita-Uka-Rexha.jpg\" alt=\"\" width=\"100\" height=\"149\" \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img class=\"alignnone wp-image-12912\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Marigona-Kozmaqi.jpg\" alt=\"\" width=\"146\" height=\"146\" \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img class=\"alignnone wp-image-12900\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Charlotte-Hilker.jpg\" alt=\"\" width=\"86\" height=\"146\" \/>\u00a0 \u00a0 \u00a0 \u00a0<img class=\"alignnone wp-image-12908\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Ardea-Cakmaku.jpg\" alt=\"\" width=\"151\" height=\"147\" \/>\u00a0 \u00a0 \u00a0 <img class=\"\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Albina-Kelmendi.jpg\" width=\"131\" height=\"148\" \/>\r\n\r\nArdita Uka-Rexha\u00a0 \u00a0 \u00a0 Marigona Kozmaqi\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Charlotte Hilker\u00a0 \u00a0 \u00a0 Ardea Cakmaku\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Albina Kelmendi","post_title":"Empower Voices, Transform Lives: Support Speech Therapy in Kosovo!","post_excerpt":"Kosovo Institute of Logopedics seeks 4,440 EUR to expand speech therapy services, aiding children's communication skills development. Join us in supporting this vital cause.\r\n\r\n&nbsp;\r\n\r\n&nbsp;","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"empower-voices-transform-lives-support-speech-therapy-in-kosovo","to_ping":"","pinged":"","post_modified":"2024-05-09 12:11:00","post_modified_gmt":"2024-05-09 11:11:00","post_content_filtered":"","post_parent":0,"guid":"https:\/\/kosovaideas.com\/?post_type=product&#038;p=12895","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":12694,"post_author":"1479","post_date":"2023-11-22 08:54:43","post_date_gmt":"2023-11-22 07:54:43","post_content":"<p style=\"text-align: justify;\"><strong>Qui sommes-nous ? <\/strong><\/p>\r\n<p style=\"text-align: justify;\">L'ONG Projet 5 Cents, fond\u00e9e en 2013, est une organisation qui organise chaque ann\u00e9e le mini-marathon bien connu \"Cours P\u00e8re No\u00ebl Cours\". L'objectif de ce mini-marathon est de vendre des costumes du P\u00e8re No\u00ebl, qui seront port\u00e9s par les participants du mini-marathon, sans distinction d'\u00e2ge et de genre. Les fonds collect\u00e9s seront d\u00e9di\u00e9s aux familles dans le besoin et aux enfants atteints de maladies graves.<\/p>\r\n<p style=\"text-align: justify;\">Initialement, le mini-marathon \"Cours P\u00e8re No\u00ebl Cours\" a commenc\u00e9 avec seulement 100 P\u00e8res No\u00ebl, aidant environ 60 familles. Au fil des ans, ce nombre a augment\u00e9 pour atteindre sa 8e ann\u00e9e d'organisation, o\u00f9 ce mini-marathon est devenu une tradition et un \u00e9v\u00e9nement important pour la capitale. Cette ann\u00e9e, 3000 P\u00e8res No\u00ebl participeront au mini-marathon.<\/p>\r\n<p style=\"text-align: justify;\">Avec l'augmentation du nombre de participants, il y a aussi une opportunit\u00e9 accrue d'aider non seulement les familles dans le besoin, mais aussi les enfants souffrant de maladies graves et trait\u00e9s \u00e0 l'h\u00f4pital p\u00e9diatrique du Centre clinique universitaire du Kosovo, en particulier dans le service d'h\u00e9matologie-oncologie de cette clinique.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Quel est notre objectif ?<\/strong><\/p>\r\n<p style=\"text-align: justify;\">Cette ann\u00e9e, l'ONG 5 Cents a d\u00e9cid\u00e9 de lever des fonds sp\u00e9cifiquement pour les enfants du service d'h\u00e9matologie-oncologie de l'h\u00f4pital p\u00e9diatrique gr\u00e2ce \u00e0 une campagne sur KOSOVAideas. L'objectif est d'all\u00e9ger les difficult\u00e9s auxquelles sont confront\u00e9s ces enfants et de rendre la nuit du changement de saison aussi agr\u00e9able que possible.<\/p>\r\n<p style=\"text-align: justify;\"><strong>De quoi avons-nous besoin ?<\/strong><\/p>\r\n<p style=\"text-align: justify;\">Gr\u00e2ce \u00e0 une communication continue avec la direction de l'h\u00f4pital p\u00e9diatrique, le service d'h\u00e9matologie-oncologie, nous avons identifi\u00e9 l'\u00e9quipement et les outils n\u00e9cessaires pour am\u00e9liorer les services de sant\u00e9 pour ces enfants. De plus, nous visons \u00e0 organiser une nuit du P\u00e8re No\u00ebl \u00e0 l'occasion de la c\u00e9l\u00e9bration du Nouvel An. L'\u00e9quipement et les outils comprennent 6 lits pour les m\u00e8res restant 24 heures avec leurs enfants, des jouets et des outils qui ont un impact sur la r\u00e9habilitation psychologique des enfants pendant le traitement, ainsi que des cadeaux pour le Nouvel An.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Comment votre soutien nous aidera-t-il ?<\/strong><\/p>\r\n<p style=\"text-align: justify;\">Votre contribution aura un impact significatif sur la vie et le traitement des enfants atteints de maladies graves, en fournissant un certain soulagement dans leur traitement et en apportant des sourires \u00e0 leurs visages lors du changement de saison. En permettant l'achat de 6 lits, vous aiderez les m\u00e8res d'enfants atteints de maladies graves \u00e0 avoir plus de facilit\u00e9 \u00e0 rester pr\u00e8s de leurs proches, car leur force donne de la force \u00e0 leurs petits.<\/p>\r\n<p style=\"text-align: justify;\">Pendant le traitement, les enfants font face \u00e0 diff\u00e9rentes peurs, de la peur des aiguilles pour la th\u00e9rapie aux autres difficult\u00e9s de leur parcours de gu\u00e9rison. Cette situation n\u00e9cessite des soins psychologiques particuliers, et votre aide en donnant des fonds pour acheter des jouets et des outils ayant un impact sur leur bien-\u00eatre psychologique pendant le traitement les aidera \u00e0 faire face plus facilement \u00e0 leur situation.<\/p>\r\n<p style=\"text-align: justify;\">Enfin, mais non moins important, votre aide et votre soutien pour permettre des cadeaux et une atmosph\u00e8re festive avec le P\u00e8re No\u00ebl lors du changement de saison ajouteront des sourires aux visages de ces enfants qui, cette nuit-l\u00e0, seront allong\u00e9s dans le service avec le seul souhait : UNE GU\u00c9RISON COMPL\u00c8TE !<\/p>\r\n<p style=\"text-align: justify;\">Budget pour le projet<\/p>\r\n<p style=\"text-align: justify;\">Lits \u2013 6 pi\u00e8ces 1 500 \u20ac<\/p>\r\n<p style=\"text-align: justify;\">Jouets divers 1 000 \u20ac<\/p>\r\n<p style=\"text-align: justify;\">Outils pour la r\u00e9habilitation psychologique - jouets sp\u00e9cifiques 1 000 \u20ac<\/p>\r\n<p style=\"text-align: justify;\">Cadeaux et mascottes pour la nuit du P\u00e8re No\u00ebl 1 000 \u20ac<\/p>\r\n<p style=\"text-align: justify;\">Frais de KOSOVAideas (10 %) 500 \u20ac<\/p>\r\n<p style=\"text-align: justify;\">Total 5 000,00 \u20ac<\/p>","post_title":"\"Soyez un P\u00e8re No\u00ebl pour les Enfants dans le Besoin - Soutenez 'Vrapo Babadimer' pour les Enfants \u00e0 la Clinique P\u00e9diatrique.\"","post_excerpt":"Le projet d'ONG \"5 Cents\" organise l'\u00e9v\u00e9nement \"Run Santa Run\" pour aider les familles et les enfants atteints de maladies graves.","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"soyez-un-pere-noel-pour-les-enfants-dans-le-besoin-soutenez-vrapo-babadimer-pour-les-enfants-a-la-clinique-pediatrique","to_ping":"","pinged":"","post_modified":"2024-03-19 08:58:39","post_modified_gmt":"2024-03-19 07:58:39","post_content_filtered":"","post_parent":0,"guid":"https:\/\/kosovaideas.com\/?post_type=product&#038;p=12694","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":12533,"post_author":"1470","post_date":"2023-10-02 08:23:32","post_date_gmt":"2023-10-02 07:23:32","post_content":"<strong>Arri\u00e8re-plan<\/strong>\r\n\r\nL'\u00c9cole sup\u00e9rieure d'art appliqu\u00e9 \u00ab Odhise Paskali \u00bb de Peja a \u00e9t\u00e9 fond\u00e9e en 1946. Depuis sa cr\u00e9ation jusqu'\u00e0 aujourd'hui, elle reste la seule institution du pays d\u00e9di\u00e9e \u00e0 l'enseignement des arts appliqu\u00e9s. Tous les professionnels artistiques de notre pays ont leurs racines dans cette \u00e9cole. Actuellement, l'\u00e9cole propose cinq cours en tant que fili\u00e8res sp\u00e9cialis\u00e9es dans l'enseignement professionnel secondaire : design textile et de mode, design d'int\u00e9rieur, design graphique, design c\u00e9ramique et direction de peinture. L'\u00e9cole accueille actuellement 300 \u00e9tudiants, avec 60 \u00e9tudiants inscrits dans chaque profil.\r\n\r\n<strong>Direction du design c\u00e9ramique<\/strong>\r\n\r\nActuellement, 60 \u00e9tudiants sont inscrits au programme de design c\u00e9ramique, dont 60 % sont des femmes. Le design c\u00e9ramique a acquis une importance significative en tant que profil en raison de l'int\u00e9r\u00eat croissant pour les inscriptions chaque ann\u00e9e.\r\n\r\nCe programme fonctionne au sein de deux ateliers bien \u00e9quip\u00e9s, offrant un environnement id\u00e9al pour le d\u00e9veloppement des \u00e9tudiants. Les \u00e9tudiants de ce cours cr\u00e9ent une vari\u00e9t\u00e9 d'\u0153uvres artistiques, notamment des accessoires d\u00e9coratifs, des vases, des plats, des sculptures et des r\u00e9pliques de divers artefacts. Beaucoup de ces r\u00e9pliques sont expos\u00e9es au mus\u00e9e du Kosovo. De plus, les \u00e9tudiants de ce programme ont particip\u00e9 activement \u00e0 de nombreuses expositions et ont pr\u00e9sent\u00e9 leurs \u0153uvres \u00e0 l'\u00e9tranger.\r\n\r\nCependant, un probl\u00e8me urgent est apparu concernant le manque de fours ad\u00e9quats pour cuire ces cr\u00e9ations en c\u00e9ramique. Actuellement, les \u00e9tudiants de ce programme travaillent avec un petit four qui ne r\u00e9unit pas les conditions n\u00e9cessaires au d\u00e9veloppement optimal de leurs comp\u00e9tences. L\u2019absence d\u2019un four adapt\u00e9, plus grand et r\u00e9guli\u00e8rement entretenu freine la progression et la formation de nombreux \u00e9tudiants. Par cons\u00e9quent, un nombre important de leurs projets restent inachev\u00e9s.\r\n\r\n<strong>Le but du projet<\/strong>\r\n\r\nCompte tenu de la r\u00e9ussite du cours de design c\u00e9ramique, du d\u00e9vouement des \u00e9tudiants dans leurs \u00e9tudes et de l'objectif de leur offrir les meilleures opportunit\u00e9s possibles d'exceller, l'objectif principal du projet est d'acqu\u00e9rir un nouveau four \u00e0 c\u00e9ramique.\r\n\r\nL'implantation d'un nouveau Four \u00e0 C\u00e9ramique am\u00e9liorerait incontestablement la qualit\u00e9 de la formation des \u00e9tudiants, attirerait potentiellement davantage d'\u00e9tudiants au programme et faciliterait la r\u00e9alisation de nombreux projets artistiques. De plus, \u00e9quiper l'\u00e9cole de ce four permettrait aux \u00e9tudiants de cr\u00e9er des \u0153uvres d'art qui pourraient am\u00e9liorer consid\u00e9rablement leur visibilit\u00e9 et leur performance dans les concours et expositions internationaux et favoriser la croissance de leurs comp\u00e9tences professionnelles.\r\n\r\n<strong>Comment votre soutien nous aidera-t-il ?<\/strong>\r\n\r\nLe co\u00fbt du nouveau four, environ 10 000 euros, repr\u00e9sente un d\u00e9fi financier important tant pour l'\u00e9cole que pour les familles des \u00e9l\u00e8ves. Votre soutien est essentiel \u00e0 la bonne r\u00e9alisation de ce projet. En participant \u00e0 la campagne de financement pour doter l'\u00e9cole d'un nouveau four \u00e0 poterie, vous aurez un impact direct sur plusieurs aspects critiques :\r\n\r\n<strong>\u00c9ducation de qualit\u00e9<\/strong>\u00a0: Votre soutien garantira que ces \u00e9tudiants re\u00e7oivent la formation professionnelle dont ils ont besoin pour exceller dans leur domaine, contribuant ainsi au d\u00e9veloppement d\u2019artistes c\u00e9ramistes hautement qualifi\u00e9s.\r\n\r\n<strong>Repr\u00e9sentation nationale<\/strong> : Avec votre aide, ces \u00e9tudiants disposeront des outils et des ressources n\u00e9cessaires pour repr\u00e9senter efficacement notre pays sur la sc\u00e8ne internationale, mettant en valeur le talent artistique et le potentiel du Kosovo.\r\n\r\n<strong>Impact g\u00e9n\u00e9rationnel<\/strong>\u00a0: Votre soutien profitera non seulement \u00e0 la g\u00e9n\u00e9ration actuelle d'\u00e9tudiants, mais laissera \u00e9galement un h\u00e9ritage aux g\u00e9n\u00e9rations futures int\u00e9ress\u00e9es \u00e0 poursuivre une carri\u00e8re dans la c\u00e9ramique. Cet investissement dans l\u2019\u00e9ducation a le potentiel de fa\u00e7onner le paysage artistique de la r\u00e9gion pour les ann\u00e9es \u00e0 venir.\r\n\r\nVotre contribution \u00e0 ce projet est inestimable et grandement appr\u00e9ci\u00e9e. Cela fera une diff\u00e9rence significative dans la vie de ces \u00e9tudiants et de la communaut\u00e9 artistique.\r\n\r\n<strong>Budget du projet<\/strong>\r\n\r\n<strong>\u00a0<\/strong>\r\n<table style=\"height: 179px;\" width=\"899\">\r\n<tbody>\r\n<tr>\r\n<td><strong>CAT\u00c9GORIE<\/strong><\/td>\r\n<td><strong>BUDGET TOTAL<\/strong><\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Four \u00e0 poterie<\/td>\r\n<td>10000\u20ac<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>10\u00a0% de frais de carte de cr\u00e9dit, de virement bancaire et KOSOVA ideas<\/td>\r\n<td>1000\u20ac<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 11.000\u20ac<\/strong>\r\n\r\n<strong>\u00a0<\/strong><strong>Project Team<\/strong>\r\n\r\n&nbsp;\r\n\r\n<strong>\u00a0 <img class=\"alignnone wp-image-12492\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/09\/IMG_2216-scaled.jpg\" alt=\"\" width=\"166\" height=\"110\" \/> <\/strong><strong>\u00a0\u00a0\u00a0 <img class=\"alignnone wp-image-12496\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/09\/IMG_2220-scaled.jpg\" alt=\"\" width=\"168\" height=\"112\" \/>\u00a0 \u00a0 \u00a0 \u00a0 <img class=\"alignnone wp-image-12500\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/09\/IMG_2230-scaled.jpg\" alt=\"\" width=\"172\" height=\"114\" \/><\/strong>\r\n\r\n<strong>\u00a0 Kastriot Blakaj\u00a0<\/strong> \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <strong>\u00a0Blerina Bytyqi\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Soreja Adzajlic<\/strong>","post_title":"\"\u00c9tincelle de cr\u00e9ativit\u00e9 : Aidez-nous \u00e0 allumer l'avenir du lyc\u00e9e 'Odhise Paskali' !\"","post_excerpt":"\"Soutenez notre projet d'acquisition d'un nouveau four \u00e0 c\u00e9ramique pour l'\u00c9cole sup\u00e9rieure d'art appliqu\u00e9 'Odhise Paskali' \u00e0 Peja, au Kosovo. Votre contribution garantira une \u00e9ducation de qualit\u00e9 aux aspirants c\u00e9ramistes, leur permettant d'exceller dans leur domaine et de repr\u00e9senter le talent artistique du Kosovo \u00e0 l'\u00e9chelle internationale. Cet investissement profite non seulement aux \u00e9tudiants actuels, mais laisse \u00e9galement un h\u00e9ritage aux g\u00e9n\u00e9rations futures int\u00e9ress\u00e9es par la c\u00e9ramique. Rejoignez-nous pour fa\u00e7onner le paysage artistique de la r\u00e9gion et avoir un impact significatif sur la vie de ces \u00e9tudiants.","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"etincelle-de-creativite-aidez-nous-a-allumer-lavenir-du-lycee-odhise-paskali","to_ping":"","pinged":"","post_modified":"2023-10-02 08:41:50","post_modified_gmt":"2023-10-02 07:41:50","post_content_filtered":"","post_parent":0,"guid":"https:\/\/kosovaideas.com\/?post_type=product&#038;p=12533","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":11565,"post_author":"1426","post_date":"2023-05-23 13:11:12","post_date_gmt":"2023-05-23 12:11:12","post_content":"<h4><strong>Qui nous sommes?<\/strong><\/h4>\r\n<p style=\"text-align: justify;\">La Fondation de la Ligue des cr\u00e9ateurs kosovars \u2013 Kosova Makers League (KML) est une plateforme \u00e9ducative non formelle qui organise le plus grand concours de robotique pour les \u00e9coles \u00e9l\u00e9mentaires et autres \u00e9tablissements d'enseignement du Kosovo qui travaillent avec des enfants \u00e2g\u00e9s de 6 \u00e0 15 ans.<\/p>\r\n<p style=\"text-align: justify;\">En organisant le plus grand concours de robotique, KML donne l'opportunit\u00e9 \u00e0 tous les enfants sans distinction de faire les premiers pas dans le domaine de la robotique et de r\u00e9aliser diverses activit\u00e9s avec un focus sur les domaines STEAM (Science, Technologie, Ing\u00e9nierie, Art et Math\u00e9matiques).\r\n\u00c0 ce jour, KML a distribu\u00e9 un total de 2100 robots \u00e9ducatifs gratuits \u00e0 234 \u00e9tablissements d'enseignement dans 30 municipalit\u00e9s du Kosovo, dont plus de 4500 \u00e9tudiants et plus de 500 enseignants ont \u00e9t\u00e9 impliqu\u00e9s.<\/p>\r\n<p style=\"text-align: justify;\">Pendant quatre ann\u00e9es cons\u00e9cutives, au concours de robotique des robots \u00e9ducatifs mBot ont \u00e9t\u00e9 utilis\u00e9s, et depuis septembre 2022, la ligue a \u00e9t\u00e9 mise \u00e0 jour avec le nouvel appareil micro Maqueen Plus. Ce nouvel appareil est moins co\u00fbteux, propose une programmation dans deux langages de programmation et fonctionne via la carte micro bit, dont la plupart des \u00e9coles \u00e9l\u00e9mentaires publiques sont d\u00e9j\u00e0 \u00e9quip\u00e9es.\r\n\u00c9tant une organisation \u00e0 but non lucratif, KML a r\u00e9alis\u00e9 tout son soutien au fil des ans gr\u00e2ce \u00e0 divers dons fournis principalement par des donateurs \u00e9trangers.\r\nCette ann\u00e9e, le concours de robotique est soutenu par l'ambassade am\u00e9ricaine au Kosovo.<\/p>\r\n\r\n<h4 style=\"text-align: justify;\"><strong>Quel est notre objectif?<\/strong><\/h4>\r\n<p style=\"text-align: justify;\">Notre objectif principal est de fournir autant de robots \u00e9ducatifs que possible afin qu'ils puissent \u00eatre distribu\u00e9s gratuitement dans les \u00e9coles \u00e9l\u00e9mentaires publiques du Kosovo, r\u00e9alisant ainsi leur num\u00e9risation. Cela permettrait au plus grand nombre d'enfants d'\u00eatre impliqu\u00e9s dans une nouvelle approche de l'\u00e9ducation, o\u00f9 la technologie n'est utilis\u00e9e que comme un outil pour encourager chez les enfants la pens\u00e9e critique et cr\u00e9ative, e travail d'\u00e9quipe et la communication, comp\u00e9tences n\u00e9cessaires pour faire face aux d\u00e9fis du si\u00e8cle dans lequel nous vivons.<\/p>\r\n\r\n<h5 style=\"text-align: justify;\"><em><strong>A travers la campagne \"un robot pour chaque enfant\", nous visons \u00e0 \u00e9quiper au moins 50% des \u00e9coles primaires publiques du pays, afin qu'un maximum d'enfants de 6 \u00e0 15 ans puissent toucher au monde de la robotique.<\/strong><\/em><\/h5>\r\n<p style=\"text-align: justify;\">De cette mani\u00e8re, un environnement inclusif et sain sera cr\u00e9\u00e9 dans les \u00e9coles primaires publiques du pays, o\u00f9 les enfants, quels que soient leur sexe, leur \u00e2ge et leur origine ethnique, se sentiront libres d'explorer et d'\u00eatre inspir\u00e9s en tant que futurs leaders de la science et de la technologie.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Comment votre soutien va-t-il nous aider?<\/strong><\/p>\r\n<p style=\"text-align: justify;\">\u00c0 ce jour, gr\u00e2ce \u00e0 des dons, KML a r\u00e9ussi \u00e0 fournir \u00e0 25 % des \u00e9coles \u00e9l\u00e9mentaires du Kosovo des robots \u00e9ducatifs gratuits, en les incluant dans notre concours \u00e9ducatif.\r\nGr\u00e2ce \u00e0 votre soutien, nous serons en mesure d'atteindre l'inclusion d'au moins 50 % du total des \u00e9coles primaires publiques du pays.\r\nC'est pourquoi notre fondation vous invite \u00e0 rejoindre la campagne \"un robot pour chaque enfant\" pour rendre cela possible ensemble. Nous vous sommes reconnaissants si vous d\u00e9cidez de contribuer, mais pas seulement, nous vous sommes reconnaissants si vous partagez notre campagne avec votre soci\u00e9t\u00e9.<\/p>\r\n\r\n<h4 style=\"text-align: justify;\"><strong>Budget<\/strong><\/h4>\r\n<img class=\"size-full wp-image-11657 alignleft\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/05\/Buxheti_ENG.png\" alt=\"\" width=\"1056\" height=\"244\" \/>\r\n<h3><\/h3>\r\n<h3><\/h3>\r\n<h3><\/h3>\r\n<h3><\/h3>\r\n<h3><\/h3>\r\n<h3><\/h3>\r\n<h3 style=\"text-align: center;\"><strong>OBJECTIFS AJOUT\u00c9S<\/strong><\/h3>\r\n<ul>\r\n \t<li style=\"text-align: justify;\">* Selon les statistiques du minist\u00e8re de l'\u00c9ducation du Kosovo, pour l'ann\u00e9e scolaire 2021\/22, 878 \u00e9coles publiques primaires et secondaires sont enregistr\u00e9es.<\/li>\r\n \t<li style=\"text-align: justify;\">* Dans le concours de robotique ouvert de la Kosova Makers League un total de 212 \u00e9coles primaires et secondaires inf\u00e9rieures publiques sont enregistr\u00e9es.<\/li>\r\n \t<li style=\"text-align: justify;\">* Afin d'atteindre l'objectif de num\u00e9risation de toutes les \u00e9coles primaires publiques du Kosovo, 666 \u00e9coles suppl\u00e9mentaires devraient \u00eatre incluses dans notre concours, \u00e9quip\u00e9es de robots \u00e9ducatifs gratuits.<\/li>\r\n \t<li style=\"text-align: justify;\">* Pour y parvenir, KML a pr\u00e9par\u00e9 deux objectifs suppl\u00e9mentaires en cas d'atteinte de l'objectif principal avec le budget susmentionn\u00e9.<\/li>\r\n<\/ul>\r\n<img class=\"size-full wp-image-11661 aligncenter\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/05\/Stretch-Goal-1.png\" alt=\"\" width=\"1056\" height=\"303\" \/>\r\n\r\n<img class=\"size-full wp-image-11665 aligncenter\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/05\/Stretch-Goal-2.png\" alt=\"\" width=\"1056\" height=\"303\" \/>\r\n<h3><\/h3>\r\n<h3 style=\"text-align: center;\"><strong>VOTRE CONTRIBUTION SI<\/strong><\/h3>\r\n<img class=\"aligncenter wp-image-11644 size-full\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/05\/Kontributi-e1685367397153.jpg\" alt=\"\" width=\"1042\" height=\"844\" \/>\r\n\r\n&nbsp;\r\n<h3 style=\"text-align: center;\"><strong> ROBOT MICRO:MAQUEEN PLUS<\/strong><\/h3>\r\n<img class=\"size-full wp-image-11556 aligncenter\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/05\/micro-Maqueen-Plus-robot-1.gif\" alt=\"\" width=\"1080\" height=\"1080\" \/>\r\n<h3><\/h3>\r\n<h3><\/h3>\r\n<h3 style=\"text-align: center;\"><strong>DATE LIMITE\r\n<img class=\"size-full wp-image-11677 aligncenter\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/05\/Timeline_Kosova-Makers-League-2023-2024-1.png\" alt=\"\" width=\"1024\" height=\"768\" \/>\r\n<\/strong><\/h3>\r\n&nbsp;\r\n<h3 style=\"text-align: center;\"><strong> KOSOVA MAKERS LEAGUE \u00c9QUIPE\r\n<\/strong><\/h3>\r\n<img class=\" wp-image-11673 aligncenter\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/05\/Team_Kosova-Makers-League.png\" alt=\"\" width=\"963\" height=\"220\" \/>","post_title":"Un robot pour chaque enfant!","post_excerpt":"\"Un robot pour chaque enfant\" vise \u00e0 num\u00e9riser les \u00e9coles \u00e9l\u00e9mentaires publiques du Kosovo.","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"un-robot-pour-chaque-enfant","to_ping":"","pinged":"","post_modified":"2023-07-17 07:43:27","post_modified_gmt":"2023-07-17 06:43:27","post_content_filtered":"","post_parent":0,"guid":"https:\/\/kosovaideas.com\/product\/nje-robot-per-cdo-femije\/","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":7032,"post_author":"1427","post_date":"2023-03-12 20:02:39","post_date_gmt":"2023-03-12 19:02:39","post_content":"BONEVET Labs x Jeunes kosovars = comp\u00e9tences techniques tout en apprenant le recyclage et la conservation.\r\n\r\nBONEVET Labs est structur\u00e9 de mani\u00e8re \u00e0 obtenir des r\u00e9sultats durables et \u00e0 long terme sur la protection de l'environnement et la r\u00e9duction de l'utilisation du plastique. Cet objectif sera atteint gr\u00e2ce \u00e0 l'int\u00e9gration de la composante d'apprentissage par projet et \u00e0 l'encouragement des activit\u00e9s pratiques tout au long des ateliers pr\u00e9vus.\r\n\r\n&nbsp;\r\n\r\n<strong>Qui sommes-nous?<\/strong>\r\n\r\nBONEVET Prishtina en collaboration avec\u00a0<a href=\"https:\/\/manifesta14.org\/participant\/driant-zeneli\/\">Driant Zeneli<\/a>\u00a0(artiste albanais), travaillent ensemble dans un projet passionnant intitul\u00e9 \"Les animaux. Il \u00e9tait une fois... dans un pr\u00e9sent\". Ce projet sera pr\u00e9sent\u00e9 \u00e0 la Biennale Manifesta, l'une des plus c\u00e9l\u00e8bres biennales d'Europe. L'id\u00e9e de cette collaboration est de pr\u00e9senter l'autruche (oiseau non volant) comme un d\u00e9fenseur de l'environnement qui r\u00e9utilise le plastique gaspill\u00e9 en objets et outils utiles. L'autruche elle-m\u00eame sera construite par BONEVET, alors que des caract\u00e9ristiques suppl\u00e9mentaires, comme le mouvement de la queue et du cou, seront ajout\u00e9es. BONEVET recyclera les d\u00e9chets plastiques tout au long de l'exposition, en utilisant un broyeur,\u00a0une extrudeuse de filaments et quatre imprimantes 3D.\u00a0Les jeunes qui participeront \u00e0 ce laboratoire pendant les heures d'ouverture de la biennale, seront form\u00e9s \u00e0 l'utilisation d'une imprimante 3D et d'un logiciel de conception, et seront encourag\u00e9s \u00e0 r\u00e9duire leur consommation de plastique au quotidien.\r\n\r\nCes ateliers se d\u00e9rouleront dans un environnement s\u00fbr, dans l'espace de la biennale. Les activit\u00e9s propos\u00e9es comprendront des tables rondes, des projets de bricolage, la conception et l'impression 3D. Cet espace sera \u00e9galement utilis\u00e9 pour projeter des films et des documentaires sur le r\u00e9chauffement de la plan\u00e8te et le changement climatique.\r\n\r\n&nbsp;\r\n\r\n<strong>Quel est notre objectif?<\/strong>\r\n\r\nGr\u00e2ce \u00e0 ce projet, plus de 150 jeunes dans tout le pays auront la possibilit\u00e9 de travailler avec des imprimantes 3D, des logiciels de conception 3D et d'apprendre le recyclage en pratique. Il a \u00e9t\u00e9 prouv\u00e9 que l'apprentissage par projet a un rendement \u00e9lev\u00e9 des investissements dans la communaut\u00e9. C'est pourquoi nous pensons que ce projet donnera une impulsion consid\u00e9rable au secteur de l'environnement ici au Kosovo.\r\n\r\n&nbsp;\r\n\r\n<strong>Comment votre soutien va-t-il nous aider?<\/strong>\r\n\r\nAvec votre aide, nous pourrons acheter le mat\u00e9riel n\u00e9cessaire pour pr\u00e9parer techniquement l'espace pour le processus de recyclage. Nous allons acheter un protocycler, qui transformera le plastique broy\u00e9 en un filament qui pourra ensuite \u00eatre utilis\u00e9 dans des imprimantes 3D.\u00a0 En plus de cela, d'autres \u00e9quipements \u00e9lectroniques seront achet\u00e9s pour rendre fonctionnels les installations et les \u0153uvres d'art. Pour plus d'informations sur Manifesta, lisez ici:\u00a0<a href=\"https:\/\/manifesta14.org\/\">www.manifesta14.org<\/a>\r\n\r\n&nbsp;\r\n\r\n<strong>Budget<\/strong>\r\n<table width=\"661\">\r\n<tbody>\r\n<tr>\r\n<td width=\"37\">1)<\/td>\r\n<td width=\"501\">Protocycler plus grindless<\/td>\r\n<td width=\"123\">\u00a0 \u00a0 \u20ac\u00a0 \u00a0 \u00a0 \u00a0 \u00a03,635.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>2)<\/td>\r\n<td>Plexi transparent\u00a08 mm 205x305 cm<\/td>\r\n<td>\u00a0 \u00a0 \u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 270.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>3)<\/td>\r\n<td>Cadre et plaques en m\u00e9tal<\/td>\r\n<td>\u00a0 \u00a0 \u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 200.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>4)<\/td>\r\n<td>Servomoteurs + \u00e9quipement \u00e9lectronique<\/td>\r\n<td>\u00a0 \u00a0 \u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 280.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>5)<\/td>\r\n<td>Taxes + frais<\/td>\r\n<td>\u00a0 \u00a0 \u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 115.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>6)<\/td>\r\n<td>10% de frais de carte de cr\u00e9dit, de virement bancaire et de plateforme<\/td>\r\n<td>\u00a0 \u00a0 \u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 500.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td><\/td>\r\n<td><strong>Total<\/strong><\/td>\r\n<td><strong>\u00a0 \u00a0 \u20ac\u00a0 \u00a0 \u00a0 \u00a0 \u00a05,000.00<\/strong><\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>","post_title":"BONEVET Labs x MANIFESTA","post_excerpt":"BONEVET Labs x kosovarische Jugendliche = technische F\u00e4higkeiten beim Lernen \u00fcber Recycling und Naturschutz.","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"bonevet-labs-x-manifesta","to_ping":"","pinged":"","post_modified":"2023-07-17 10:12:30","post_modified_gmt":"2023-07-17 09:12:30","post_content_filtered":"","post_parent":0,"guid":"https:\/\/ki2023.kosovaideas.com\/product\/bonevet-labs-x-manifesta\/","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":7244,"post_author":"1428","post_date":"2022-03-30 13:53:44","post_date_gmt":"2022-03-30 12:53:44","post_content":"<strong>Qui sommes nous?<\/strong>\r\n\r\n&nbsp;\r\n\r\nL'ONG SAKUNTALA a \u00e9t\u00e9 cr\u00e9\u00e9e en 2008 dans le but de cr\u00e9er un environnement stable au Kosovo pour l'int\u00e9gration des communaut\u00e9s minoritaires afin de repr\u00e9senter leur position, les droits de l'homme et de promouvoir les valeurs d'\u00e9galit\u00e9, d'inclusion sociale et de d\u00e9veloppement socio-\u00e9conomique pour tous les individus et groupes. ind\u00e9pendamment de leur appartenance ethnique, religieuse, sexuelle ou sociale. Entre autres, l'organisation a \u00e9t\u00e9 cr\u00e9\u00e9e pour promouvoir et pr\u00e9server les int\u00e9r\u00eats de la diversit\u00e9, les valeurs d'\u00e9galit\u00e9, de dialogue et de solidarit\u00e9.\r\n\r\n&nbsp;\r\n\r\n<strong>Quel est notre objectif?<\/strong>\r\n\r\n&nbsp;\r\n\r\nLes femmes des communaut\u00e9s rom, ashkali et \u00e9gyptienne sont victimes de discrimination, ont un acc\u00e8s limit\u00e9 \u00e0 l'emploi, \u00e0 l'\u00e9ducation et aux soins de sant\u00e9, et ce ne sont l\u00e0 que quelques-uns des facteurs qui contribuent \u00e0 l'oppression et \u00e0 la marginalisation profond\u00e9ment enracin\u00e9es des femmes des minorit\u00e9s. communaut\u00e9s. Le manque de scolarisation et la discrimination sexuelle et ethnique \u00e0 l'encontre de ces femmes sont des obstacles importants \u00e0 leur int\u00e9gration dans la soci\u00e9t\u00e9 kosovare.\r\n\r\n&nbsp;\r\n\r\nLe but de ce projet est donc:\r\n<ol>\r\n \t<li>Am\u00e9liorer les comp\u00e9tences des femmes et des filles roms gr\u00e2ce \u00e0 une formation professionnelle aux activit\u00e9s artisanales.<\/li>\r\n \t<li>Am\u00e9liorer le d\u00e9veloppement socio-\u00e9conomique, promouvoir la cr\u00e9ativit\u00e9 traditionnelle et renforcer leur coop\u00e9ration avec le march\u00e9 priv\u00e9, les ONG f\u00e9minines, les institutions culturelles et locales.<\/li>\r\n<\/ol>\r\n&nbsp;\r\n\r\nGr\u00e2ce aux activit\u00e9s susmentionn\u00e9es, leurs comp\u00e9tences en mati\u00e8re d'artisanat seront am\u00e9lior\u00e9es par une formation professionnelle, suivie de la promotion de leurs produits et de leur vente sur le march\u00e9 priv\u00e9, am\u00e9liorant ainsi leurs conditions de vie. Ce sera une force motrice pour la promotion et la pr\u00e9servation des valeurs culturelles ainsi que le d\u00e9veloppement socio-\u00e9conomique des femmes et des filles roms. Ces formations ont eu lieu auparavant et ont connu un grand succ\u00e8s, mais nous voulons r\u00e9aliser quelque chose \u00e0 plus long terme et que les femmes ne s'arr\u00eatent pas apr\u00e8s avoir termin\u00e9 la formation, mais continuent \u00e0 promouvoir leur travail. Par cons\u00e9quent, une exposition avec ces objets artisanaux sera organis\u00e9e, avec la participation de la soci\u00e9t\u00e9 civile, des ONG culturelles, des institutions locales, du secteur priv\u00e9 et des associations d'artisans afin de promouvoir les produits artisanaux des femmes et des filles roms.\r\n\r\n&nbsp;\r\n\r\n<strong>Comment votre soutien va-t-il nous aider?<\/strong>\r\n\r\n<strong>\u00a0<\/strong>\r\n\r\nAvec les fonds qui seront r\u00e9colt\u00e9s, le mat\u00e9riel n\u00e9cessaire sera achet\u00e9 pour d\u00e9marrer la formation avec ces femmes et jeunes filles de la communaut\u00e9 rom. Ce projet renforcera leurs comp\u00e9tences en mati\u00e8re d'artisanat traditionnel gr\u00e2ce \u00e0 la formation professionnelle. Des femmes \u00e2g\u00e9es de 18 \u00e0 50 ans seront s\u00e9lectionn\u00e9es pour les activit\u00e9s. La formation sera organis\u00e9e dans la municipalit\u00e9 de Prizren, \u00e0 l'Institut Yunus Emre, un institut turc qui a sa branche au Kosovo, \u00e0 Prizren et \u00e0 Peja. La formation durera 4-5 mois et sera anim\u00e9e par des animatrices, des formatrices qui prodigueront des conseils sur l'autonomisation des femmes \u00e0 travers l'artisanat. Les b\u00e9n\u00e9ficiaires directs de ce projet sont les femmes et les filles de la communaut\u00e9 rom de la municipalit\u00e9 de Prizren.\r\n\r\n<b>Budget<\/b>\r\n\r\nTotal\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 2,400.00\r\n<table width=\"679\">\r\n<tbody>\r\n<tr>\r\n<td width=\"33\">1)<\/td>\r\n<td width=\"523\">Mat\u00e9riel (tissu) pour la peinture<\/td>\r\n<td width=\"123\">\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 400.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>2)<\/td>\r\n<td>Peintures acryliques pour la peinture sur verre et mat\u00e9riaux<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 200.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>3)<\/td>\r\n<td>Cadres<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 150.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>4)<\/td>\r\n<td>Miroirs et contreplaqu\u00e9<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 190.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>5)<\/td>\r\n<td>Fleurs d\u00e9coratives s\u00e9ch\u00e9es<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 200.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>6)<\/td>\r\n<td>Plats en verre avec supports, vases d\u00e9coratifs et bougeoirs<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 120.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>7)<\/td>\r\n<td>Fil \u00e0 broder et fil d'or<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 200.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>8)<\/td>\r\n<td>Dentelle, paniers, papier pour la conception, etc.<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 150.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>9)<\/td>\r\n<td>Frais de transport<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 150.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>10)<\/td>\r\n<td>Frais d'exposition<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 300.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>11)<\/td>\r\n<td>Banners<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 100.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>12)<\/td>\r\n<td>10% de frais de carte de cr\u00e9dit, de virement bancaire et de plateforme<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 240.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td><\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>","post_title":"Fuqizimi i grave dhe vajzave rome p\u00ebrmes artizanatit","post_excerpt":"<div class=\"description\">\r\n<div class=\"description\">Ce projet renforcera les comp\u00e9tences des femmes et des filles roms en mati\u00e8re d'artisanat traditionnel gr\u00e2ce \u00e0 la formation professionnelle.<\/div>\r\n<\/div>","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"fuqizimi-i-grave-dhe-vajzave-rome-permes-artizanatit","to_ping":"","pinged":"","post_modified":"2023-07-17 10:16:02","post_modified_gmt":"2023-07-17 09:16:02","post_content_filtered":"","post_parent":0,"guid":"https:\/\/ki2023.kosovaideas.com\/product\/fuqizimi-i-grave-dhe-vajzave-rome-permes-artizanatit\/","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":7256,"post_author":"627","post_date":"2021-09-22 14:09:37","post_date_gmt":"2021-09-22 13:09:37","post_content":"<strong>Galeria 17<\/strong>\r\n\r\nShtat\u00ebmb\u00ebdhjet\u00eb (17) dans la continuit\u00e9 de la r\u00e9alisation de sa mission et de sa contribution \u00e0 la sc\u00e8ne artistique, apporte \u00e0 Prishtina un nouvel espace d\u2019exposition : la Galeria 17. La galerie mettra l\u2019accent sur les questions sociales. Les artistes et les conservateurs sont invit\u00e9s \u00e0 exp\u00e9rimenter des concepts, des id\u00e9es et de l\u2019espace, offrant des expositions audacieuses dans le contenu qui cr\u00e9ent le dialogue et favorisent le d\u00e9bat public.\r\n\r\n<strong>Qui sommes-nous?<\/strong>\r\n\r\nDix-sept (17) est une organisation \u00e0 but non lucratif \u00e9tablie \u00e0 Prishtina, au Kosovo, en 2018. Centr\u00e9e sur l\u2019exp\u00e9rience et la n\u00e9cessit\u00e9 de moderniser les espaces publics alternatifs, nous avons \u00e9t\u00e9 enregistr\u00e9e comme une fondation qui vise \u00e0 favoriser un changement positif dans la soci\u00e9t\u00e9 en favorisant la vitalit\u00e9 culturelle et la cr\u00e9ativit\u00e9. Notre mission est de favoriser l\u2019activisme culturel pour le d\u00e9veloppement social. 17 a trois programmes : Art &amp; Culture, Civic Activism et Project Space. 17 est bas\u00e9 \u00e0 Prishtina, mais couvre toutes les r\u00e9gions du Kosovo avec ses activit\u00e9s.\r\n\r\nJusqu\u2019\u00e0 pr\u00e9sent, il existe de nombreuses initiatives auto-organis\u00e9es, cr\u00e9ant des opportunit\u00e9s pour le d\u00e9veloppement de l\u2019art et de la culture, ainsi que d\u2019encourager les citoyens du pays \u00e0 participer \u00e0 la vie publique \u00e0 travers les arts, la culture, l\u2019\u00e9ducation, le militantisme civique et l\u2019inclusion.\r\n\r\n&nbsp;\r\n\r\n<strong>Quel est notre but?<\/strong>\r\n\r\n&nbsp;\r\n\r\nSous l\u2019impulsion d\u2019une sc\u00e8ne ind\u00e9pendante d\u2019artistes talentueux et motiv\u00e9s et sans repr\u00e9sentation internationale dans un syst\u00e8me d\u2019art fragile ainsi qu\u2019avec une infrastructure minimale d\u2019art contemporain, elle a entrepris de r\u00e9articuler toute l\u2019activit\u00e9, y compris la Galeria 17.\r\n\r\nLa Galeria 17 se pr\u00e9sente comme un d\u00e9sir et un besoin d\u2019inclusivit\u00e9 et de durabilit\u00e9 d\u2019une sc\u00e8ne artistique en fermentation, o\u00f9 l\u2019exigence de nouveaux espaces d\u2019exp\u00e9rimentation est vitale. Situ\u00e9e non pas au centre, mais dans l\u2019un des plus anciens quartiers de la capitale, la galerie peut \u00eatre per\u00e7ue comme l\u2019espace d\u2019une conque qui surgit avec la palourde qui pousse, s\u2019adapte et se transforme en fonction des besoins de d\u00e9veloppement, tout comme l\u2019espace public commun refl\u00e8te notre structure sociale dans les labyrinthes du progr\u00e8s urbain. Par cons\u00e9quent, fournir un espace complet pour la recherche, l\u2019\u00e9ducation, l\u2019activisme, l\u2019exp\u00e9rimentation artistique ainsi que la cr\u00e9ation de conditions pour la repr\u00e9sentation de l\u2019art et des artistes reste un objectif en soi.\r\n\r\n&nbsp;\r\n\r\nLa mission de Galeria 17 est de favoriser la r\u00e9flexion critique en identifiant et en soutenant des voix audacieuses qui permettent de nouvelles perspectives \u00e0 travers les pratiques artistiques contemporaines.\r\n\r\n&nbsp;\r\n\r\n<strong>Comment votre soutien nous aidera-t-il?<\/strong>\r\n\r\n&nbsp;\r\n\r\nAvec votre soutien, nous pourrons poursuivre la r\u00e9novation de l\u2019espace qui servira non seulement de galerie mais aussi d\u2019espace exp\u00e9rimental pour les artistes. Votre soutien, en plus de nous aider \u00e0 rendre l\u2019espace utilisable, \u00e0 court et \u00e0 long terme contribuera \u00e0 cr\u00e9er les conditions propices \u00e0 la recherche, \u00e0 l\u2019\u00e9ducation, au militantisme et \u00e0 l\u2019exp\u00e9rimentation artistique.\r\n\r\nVotre soutien ajoutera de la valeur \u00e0 ce projet et \u00e9l\u00e8vera la voix pour l\u2019importance des institutions ind\u00e9pendantes et inclusives, qui fournissent des structures de qualit\u00e9 au service de l\u2019infrastructure manquante et bien n\u00e9cessaire pour notre contexte - dans le but d\u2019autosuffisance.\r\n\r\n&nbsp;\r\n\r\n<strong>De quoi avons-nous besoin?<\/strong>\r\n\r\n&nbsp;\r\n\r\nLa restauration des portes, des planchers et des tuiles ne sera que quelques-uns des aspects qui aideront \u00e0 adapter l\u2019espace de la galerie. Une fois que nous aurons termin\u00e9 les premi\u00e8res interventions, nous aurons besoin d\u2019\u00e9quipement et d\u2019installation d\u2019\u00e9clairage, des panneaux et de l\u2019inventaire n\u00e9cessaires. Nous visons \u00e0 rendre cet espace fonctionnel avec une s\u00e9rie d\u2019\u0153uvres qui rendront la galerie accessible et en m\u00eame temps r\u00e9pondre aux besoins de la communaut\u00e9 artistique d\u2019exposer leurs \u0153uvres et plus encore.\r\n\r\nBudget\r\n\r\nTotal\u00a0\u20ac 15\u00a0000,00\r\n<table width=\"543\">\r\n<tbody>\r\n<tr>\r\n<td width=\"25\">1)<\/td>\r\n<td width=\"426\">Adaptation de l\u2019espace pour une galerie (restauration des portes, du plancher et des carreaux)<\/td>\r\n<td width=\"92\">\u00a0\u20ac 2\u00a0400,00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>2)<\/td>\r\n<td>Installation des panneaux<\/td>\r\n<td>\u00a0\u20ac 2\u00a0800,00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>3)<\/td>\r\n<td>\u00c9clairage, \u00e9quipement et installation<\/td>\r\n<td>\u00a0\u20ac 3\u00a0000,00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>4)<\/td>\r\n<td>Projecteurs<\/td>\r\n<td>\u00a0\u20ac 1\u00a0500,00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>5)<\/td>\r\n<td>Syst\u00e8me de sonorisation et installation<\/td>\r\n<td>\u00a0\u20ac 1\u00a0800,00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>6)<\/td>\r\n<td>Inventaire pour la galerie<\/td>\r\n<td>\u00a0\u20ac 2\u00a0000,00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>7)<\/td>\r\n<td>10% carte de cr\u00e9dit, transfert de banque et frais de la plateforme<\/td>\r\n<td>\u00a0\u20ac 1\u00a0500,00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td><\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n&nbsp;\r\n\r\nFilming &amp; editing: Leart Rama\r\nK2.0 video: Tr\u00ebndelin\u00eb Halili","post_title":"Galeria 17","post_excerpt":"<span style=\"font-weight: 400;\">Un espace pour l\u2019\u00e9ducation, l\u2019activisme et l\u2019exp\u00e9rimentation artistique audacieuse.<\/span>","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"galeria-17","to_ping":"","pinged":"","post_modified":"2023-07-17 10:29:52","post_modified_gmt":"2023-07-17 09:29:52","post_content_filtered":"","post_parent":0,"guid":"https:\/\/ki2023.kosovaideas.com\/product\/galeria-17\/","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"}],"wpcf_project_listing":[{"ID":14771,"post_author":"1518","post_date":"2024-09-23 11:27:57","post_date_gmt":"2024-09-23 10:27:57","post_content":"Le programme du matin sur Radio T\u00e9l\u00e9vision du Kosovo lance une nouvelle campagne de collecte de fonds visant \u00e0 cr\u00e9er des espaces r\u00e9cr\u00e9atifs dans les \u00e9coles primaires des zones rurales du Kosovo. Cette initiative, appel\u00e9e \"Apprendre et Jouer\", cherche \u00e0 transformer les environnements scolaires en espaces attrayants pour l'apprentissage et le jeu, offrant ainsi plus d'opportunit\u00e9s aux \u00e9l\u00e8ves de se d\u00e9velopper \u00e0 la fois sur le plan \u00e9ducatif et social.\r\n\r\nAvec votre participation, nous vous invitons \u00e0 contribuer financi\u00e8rement pour s\u00e9curiser le mat\u00e9riel n\u00e9cessaire et aider \u00e0 cr\u00e9er des espaces r\u00e9cr\u00e9atifs qui am\u00e9lioreront l'exp\u00e9rience scolaire des \u00e9l\u00e8ves du primaire. Chaque contribution est r\u00e9alis\u00e9e \u00e0 travers un processus enti\u00e8rement transparent, o\u00f9 chaque don aura un impact direct sur la cr\u00e9ation de ces espaces.\r\n\r\n<strong>Pourquoi \"Apprendre et Jouer\" ?<\/strong>\r\n\r\nLes espaces r\u00e9cr\u00e9atifs sont essentiels pour cr\u00e9er un environnement plus engageant et motivant pour les enfants, surtout dans les zones rurales. Ces lieux ne sont pas seulement des espaces de jeu \u2013 ils offrent des opportunit\u00e9s de stimulation, de d\u00e9veloppement des comp\u00e9tences sociales, et encouragent une plus grande implication scolaire. Ces espaces sont con\u00e7us pour offrir un \u00e9quilibre sain entre l'apprentissage et le jeu, renfor\u00e7ant ainsi le lien des \u00e9l\u00e8ves avec l'\u00e9cole et aidant \u00e0 pr\u00e9venir l'abandon scolaire.\r\n\r\n<strong>Que proposent ces espaces ?<\/strong>\r\n<ul>\r\n \t<li>Des zones con\u00e7ues pour diverses activit\u00e9s, y compris la lecture, les arts et les jeux.<\/li>\r\n \t<li>Des jeux et des activit\u00e9s physiques, comme le ping-pong, pour promouvoir \u00e0 la fois la sant\u00e9 physique et mentale.<\/li>\r\n \t<li>Des coins collaboratifs et de d\u00e9veloppement social, o\u00f9 les enfants peuvent apprendre en jouant en groupe, renfor\u00e7ant ainsi leurs comp\u00e9tences en communication et en interaction sociale.<\/li>\r\n \t<li>Des mini-biblioth\u00e8ques et des coins de lecture, encourageant les \u00e9l\u00e8ves \u00e0 explorer le monde \u00e0 travers les livres et \u00e0 cultiver un amour pour la connaissance.<\/li>\r\n \t<li>Des espaces color\u00e9s et vibrants avec des murs d\u00e9cor\u00e9s, cr\u00e9ant une atmosph\u00e8re chaleureuse et motivante pour les enfants.<\/li>\r\n<\/ul>\r\nEn fonction des fonds r\u00e9colt\u00e9s, nous visons \u00e0 fournir \u00e0 chaque \u00e9cole :\r\n<ul>\r\n \t<li>Une table de ping-pong<\/li>\r\n \t<li>Un coin lecture avec des coussins confortables<\/li>\r\n \t<li>Un coin mini-biblioth\u00e8que<\/li>\r\n \t<li>La d\u00e9coration et la peinture des espaces pour cr\u00e9er une ambiance anim\u00e9e et accueillante<\/li>\r\n<\/ul>\r\nLe montant requis est de <strong>3,300 \u20ac<\/strong>, ce qui inclut une commission administrative de 10 % sur la plateforme KOSOVAideas.\r\n\r\n<strong>Comment pouvez-vous contribuer ?<\/strong>\r\n\r\nVotre contribution peut faire une diff\u00e9rence significative dans la vie des enfants des zones rurales du Kosovo. Chaque aide, m\u00eame minime, contribuera \u00e0 b\u00e2tir un avenir meilleur pour les jeunes g\u00e9n\u00e9rations. Rejoignez-nous et faites partie de cette initiative pour cr\u00e9er un environnement plus heureux, plus sain et plus motivant pour nos \u00e9l\u00e8ves.\r\n\r\n<strong>Project Team<\/strong>\r\n\r\n<img class=\"alignnone wp-image-14738 size-thumbnail\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/09\/Trendelina-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>\u00a0 \u00a0 \u00a0 <img class=\"alignnone wp-image-14742 size-thumbnail\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/09\/Valtona-rotated-e1727077479833.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>\u00a0 \u00a0 \u00a0 <img class=\"alignnone wp-image-14733 size-thumbnail\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/09\/RTK-Llogo-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>\r\n\r\n<strong>Tr\u00ebndelin\u00eb Bucolli\u00a0 \u00a0 \u00a0Valtona Kelmendi\u00a0 \u00a0 \u00a0Radio management<\/strong>\r\n\r\nAuthor Host\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Author Host","post_title":"\"Learn and Play\" \u2013 Cr\u00e9er des espaces r\u00e9cr\u00e9atifs pour les enfants du Kosovo","post_excerpt":"La campagne \"Learn and Play\" de Radio T\u00e9l\u00e9vision du Kosovo cr\u00e9e des espaces r\u00e9cr\u00e9atifs dans les \u00e9coles rurales. Votre soutien fournit des \u00e9quipements essentiels pour am\u00e9liorer l'apprentissage et le jeu des \u00e9l\u00e8ves. Rejoignez-nous pour faire la diff\u00e9rence !","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"learn-and-play-creer-des-espaces-recreatifs-pour-les-enfants-du-kosovo","to_ping":"","pinged":"","post_modified":"2024-09-23 12:50:02","post_modified_gmt":"2024-09-23 11:50:02","post_content_filtered":"","post_parent":0,"guid":"https:\/\/kosovaideas.com\/?post_type=product&#038;p=14771","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":14410,"post_author":"1515","post_date":"2024-08-15 07:33:26","post_date_gmt":"2024-08-15 06:33:26","post_content":"<div class=\"flex max-w-full flex-col flex-grow\">\r\n<div class=\"min-h-[20px] text-message flex w-full flex-col items-end gap-2 whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 overflow-x-auto\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"3a17d53c-4b09-4f9c-ac94-3f3d313a2858\">\r\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\r\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\r\n\r\n<strong>POURQUOI PRISHTINA A-T-ELLE BESOIN D'UN CIN\u00c9MA ET D'UN TH\u00c9\u00c2TRE EN PLEIN AIR POUR LES JEUNES DE PLUS DE 10 ANS ?<\/strong> Prishtina, la capitale du Kosovo avec une population diversifi\u00e9e et dynamique, poss\u00e8de un riche patrimoine culturel. Cependant, la ville manque d'une plateforme d\u00e9di\u00e9e o\u00f9 les jeunes peuvent explorer et exprimer leurs talents dans le cin\u00e9ma et le th\u00e9\u00e2tre. Bien que des \u00e9v\u00e9nements occasionnels soient organis\u00e9s, il existe un besoin pour un espace structur\u00e9 et durable o\u00f9 les jeunes esprits peuvent r\u00e9guli\u00e8rement s'engager dans les arts du spectacle. Malgr\u00e9 ce manque, l'int\u00e9r\u00eat et le talent parmi les jeunes de Prishtina ne manquent pas. Ce qui manque, c'est un environnement favorable o\u00f9 ces jeunes individus peuvent canaliser leur cr\u00e9ativit\u00e9 et leur passion pour les arts. Actuellement, les options de divertissement et de socialisation pour les jeunes se limitent aux caf\u00e9s et restaurants.\r\n\r\n<strong>QUEL EST NOTRE OBJECTIF ?<\/strong> Le Cin\u00e9ma et Th\u00e9\u00e2tre en Plein Air de Prishtina vise \u00e0 cr\u00e9er un espace culturel informel o\u00f9 les jeunes de 10 ans et plus peuvent s'immerger dans le monde du cin\u00e9ma et du th\u00e9\u00e2tre. Nos objectifs sont les suivants :\r\n<ol>\r\n \t<li><strong>\u00c9ducation et exposition culturelle :<\/strong>\r\n<ul>\r\n \t<li><strong>Projections de films et de documentaires :<\/strong> Organiser r\u00e9guli\u00e8rement des projections de films classiques et contemporains pour \u00e9largir les horizons culturels et encourager l'appr\u00e9ciation de diff\u00e9rents styles et genres cin\u00e9matographiques.<\/li>\r\n \t<li><strong>Organisation de performances musicales et th\u00e9\u00e2trales :<\/strong> Offrir des plateformes pour des performances en direct, encourageant les jeunes \u00e0 s'engager dans des productions musicales et th\u00e9\u00e2trales, am\u00e9liorant ainsi leurs comp\u00e9tences artistiques.<\/li>\r\n \t<li><strong>Organisation d'\u00e9v\u00e9nements litt\u00e9raires et artistiques :<\/strong> Promouvoir l'expression litt\u00e9raire et artistique \u00e0 travers des lectures de po\u00e9sie, des clubs de lecture, des expositions d'art et des ateliers de dessin.<\/li>\r\n<\/ul>\r\n<\/li>\r\n \t<li><strong>D\u00e9veloppement des comp\u00e9tences et expression :<\/strong>\r\n<ul>\r\n \t<li><strong>Soutien aux jeunes artistes :<\/strong> Offrir des opportunit\u00e9s aux jeunes artistes dans le cin\u00e9ma, la musique, les arts et d'autres disciplines pour montrer leurs talents.<\/li>\r\n \t<li><strong>Organisation d'ateliers et de cours :<\/strong> Faciliter des ateliers \u00e9ducatifs et des cours sur divers aspects de la production cin\u00e9matographique et th\u00e9\u00e2trale, y compris le jeu d'acteur, la r\u00e9alisation, l'\u00e9criture de sc\u00e9narios, la sc\u00e9nographie et la production technique.<\/li>\r\n<\/ul>\r\n<\/li>\r\n \t<li><strong>Durabilit\u00e9 \u00e0 long terme :<\/strong>\r\n<ul>\r\n \t<li><strong>D\u00e9veloppement d'un plan triennal :<\/strong> Cr\u00e9er un plan durable pour assurer la long\u00e9vit\u00e9 du club et sa contribution continue \u00e0 la sc\u00e8ne culturelle de Prishtina. Cela inclut la s\u00e9curisation d'un financement \u00e0 long terme, l'\u00e9tablissement de partenariats et la mise en \u0153uvre de strat\u00e9gies de gestion efficaces.<\/li>\r\n<\/ul>\r\n<\/li>\r\n \t<li><strong>Engagement communautaire et impact social :<\/strong>\r\n<ul>\r\n \t<li><strong>Promotion de l'inclusivit\u00e9 :<\/strong> Cr\u00e9er un environnement inclusif o\u00f9 tous les jeunes, quel que soit leur milieu socio-\u00e9conomique, peuvent participer et b\u00e9n\u00e9ficier des activit\u00e9s du club.<\/li>\r\n \t<li><strong>Am\u00e9lioration des comp\u00e9tences sociales :<\/strong> \u00c0 travers des projets collaboratifs et des activit\u00e9s de groupe, aider les participants \u00e0 d\u00e9velopper des comp\u00e9tences sociales essentielles telles que le travail d'\u00e9quipe, la communication et le leadership.<\/li>\r\n \t<li><strong>Renforcement des liens communautaires :<\/strong> Engager la communaut\u00e9 au sens large en invitant les familles et les r\u00e9sidents \u00e0 assister aux performances et spectacles, renfor\u00e7ant ainsi un sentiment de communaut\u00e9 et d'identit\u00e9 culturelle partag\u00e9e.<\/li>\r\n<\/ul>\r\n<\/li>\r\n \t<li><strong>D\u00e9veloppement personnel et autonomisation :<\/strong>\r\n<ul>\r\n \t<li><strong>Renforcement de la confiance en soi :<\/strong> Fournir un environnement de soutien o\u00f9 les jeunes peuvent renforcer leur confiance en eux gr\u00e2ce \u00e0 la performance et \u00e0 l'expression cr\u00e9ative.<\/li>\r\n \t<li><strong>Encouragement de la pens\u00e9e critique :<\/strong> \u00c0 travers des discussions et des analyses de films et de performances, encourager les participants \u00e0 penser de mani\u00e8re critique et \u00e0 d\u00e9velopper leurs propres perspectives sur diverses questions culturelles et sociales.<\/li>\r\n \t<li><strong>Promotion du bien-\u00eatre \u00e9motionnel :<\/strong> Offrir un espace s\u00fbr o\u00f9 les jeunes peuvent exprimer leurs sentiments et pens\u00e9es de mani\u00e8re cr\u00e9ative, contribuant \u00e0 leur bien-\u00eatre mental et \u00e9motionnel global.<\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ol>\r\nEn cr\u00e9ant ce club, nous visons \u00e0 dynamiser la sc\u00e8ne culturelle de Prishtina et \u00e0 am\u00e9liorer la vie sociale de nos citoyens, en particulier les jeunes. Nous pr\u00e9voyons de collaborer avec diverses organisations pour assurer l'inclusivit\u00e9 et offrir un acc\u00e8s gratuit ou subventionn\u00e9 \u00e0 ceux qui en ont besoin.\r\n\r\n<strong>QUI SOMMES-NOUS ?<\/strong>\r\n\r\nLe Centre Culturel pour Enfants (QKF) de Prishtina a \u00e9t\u00e9 \u00e9tabli le 19 novembre 1961. La vision du Centre Culturel pour Enfants est de cr\u00e9er des exp\u00e9riences artistiques diversifi\u00e9es pour cultiver l'amour des arts, aidant les jeunes groupes d'\u00e2ge \u00e0 faire de l'art, de la musique et de la danse une partie de leur vie. Le Centre Culturel pour Enfants de Prishtina m\u00e8ne ses activit\u00e9s dans les locaux du \"Palais de la Jeunesse\" \u00e0 travers l'organisation de divers secteurs tels que la musique, le groupe litt\u00e9raire, le groupe de danse, le groupe de th\u00e9\u00e2tre et le club des jeunes ambassadeurs. Au sein de ce centre, les enfants \u00e2g\u00e9s de 6 \u00e0 16 ans sont admis et engag\u00e9s en fonction de leur volont\u00e9, de leurs comp\u00e9tences et de leur talent. Les enfants, \u00e0 travers leurs activit\u00e9s dans divers secteurs, participent souvent \u00e0 des \u00e9v\u00e9nements tant sur le plan national qu'international, tels que des festivals et diverses comp\u00e9titions. Ces participations ont abouti \u00e0 de nombreux dipl\u00f4mes et diff\u00e9rentes reconnaissances. Les r\u00e9alisations qui distinguent et soulignent le Centre Culturel pour Enfants sont les diverses personnalit\u00e9s dans la vie publique et artistique qui ont fait partie du QKF dans diff\u00e9rents secteurs.\r\n\r\n<strong>DE QUOI AVONS-NOUS BESOIN ?<\/strong>\r\n\r\nPour concr\u00e9tiser cette vision, nous avons besoin de votre soutien pour financer :\r\n\r\n\u2022 Projecteur vid\u00e9o de qualit\u00e9 pour les espaces ouverts, \u00e9quipement audio et \u00e9quipement technologique suppl\u00e9mentaire \u2013 3 000 \u20ac\r\n\r\n\u2022 G\u00e9n\u00e9rateur, c\u00e2bles et \u00e9quipement d'\u00e9clairage \u2013 1 500 \u20ac\r\n\r\n\u2022 Mat\u00e9riel de soutien tel que des chaises, des tapis et des nattes \u2013 1 300 \u20ac\r\n\r\n\u2022 Frais de programme (location de films et organisation de performances) \u2013 1 550 \u20ac\r\n\r\n\u2022 Logistique de soutien \u2013 2 000 \u20ac \u2022\r\n\r\nFrais d'administration de 10 % sur KOSOVAideas\r\n\r\nTotal :<strong> 10 390 \u20ac<\/strong>\r\n\r\n<strong>COMMENT VOTRE SOUTIEN AIDERA-T-IL EXACTEMENT ?<\/strong> Vos dons nous aideront \u00e0 acqu\u00e9rir l'\u00e9quipement technique n\u00e9cessaire et \u00e0 cr\u00e9er un espace confortable et accueillant pour nos membres. En finan\u00e7ant cette initiative, vous contribuerez \u00e0 l'enrichissement culturel de la jeunesse de Prishtina, en leur offrant des opportunit\u00e9s de d\u00e9velopper leurs comp\u00e9tences, d'exprimer leur cr\u00e9ativit\u00e9 et de s'engager dans l'art et la culture.\r\n\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"mt-1 flex gap-3 empty:hidden -ml-2\">\r\n<div class=\"items-center justify-start rounded-xl p-1 flex\">\r\n<div class=\"flex items-center\"><strong>PROJECT TEAM<\/strong><\/div>\r\n<\/div>\r\n<\/div>\r\n<img class=\"alignnone wp-image-14397\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/08\/Ariana-1-300x260.jpg\" alt=\"\" width=\"187\" height=\"162\" \/>\u00a0 \u00a0 <img class=\"alignnone wp-image-14401\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/08\/Foto-247x300.jpg\" alt=\"\" width=\"137\" height=\"166\" \/>\u00a0 \u00a0 <img class=\"alignnone wp-image-14405\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/08\/Muhamet-Jashanica-300x300.jpg\" alt=\"\" width=\"166\" height=\"166\" \/> <img class=\"alignnone wp-image-14457\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/08\/Jetlira-300x200.jpg\" alt=\"\" width=\"250\" height=\"166\" \/> <img class=\"alignnone wp-image-14461\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/08\/Gentrit-Zogejani-240x300.jpg\" alt=\"\" width=\"167\" height=\"209\" \/>\r\n\r\n<strong>Ariana Kasapolli\u00a0 \u00a0<\/strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <strong>Albana Isufi<\/strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<strong>Muhamet Jashanica\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Jetlira Ademi\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Gentrit Zogejani<\/strong>\r\n\r\n&nbsp;","post_title":"Inspirez la jeunesse de Prishtina : Lib\u00e9rez la cr\u00e9ativit\u00e9 \u00e0 travers le cin\u00e9ma et le th\u00e9\u00e2tre en plein air","post_excerpt":"Alimentez les r\u00eaves de la jeunesse de Prishtina\u2014aidez-les \u00e0 explorer, s'exprimer et s'\u00e9panouir gr\u00e2ce au cin\u00e9ma et au th\u00e9\u00e2tre en plein air.","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"inspirez-la-jeunesse-de-prishtina-liberez-la-creativite-a-travers-le-cinema-et-le-theatre-en-plein-air","to_ping":"","pinged":"","post_modified":"2024-08-15 07:36:48","post_modified_gmt":"2024-08-15 06:36:48","post_content_filtered":"","post_parent":0,"guid":"https:\/\/kosovaideas.com\/?post_type=product&#038;p=14410","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":13053,"post_author":"10","post_date":"2024-03-26 15:08:13","post_date_gmt":"2024-03-26 14:08:13","post_content":"<strong>Qui sommes nous?<\/strong>\r\n\r\nLa Fondation IPKO (IF) n\u2019est pas seulement une fondation ; nous sommes des catalyseurs de changement. Notre mission fait \u00e9cho aux r\u00eaves d\u2019innombrables filles \u00e0 travers le Kosovo. Depuis 25 ans, IF se consacre \u00e0 former les futurs dirigeants du Kosovo qui exploiteront la puissance de la technologie pour relever de front les d\u00e9fis locaux et nationaux.\r\n\r\nNous avons soutenu des dizaines de milliers de filles \u00e0 travers nos programmes, notamment Girls in ICT, Women in Cyber, WikiAcademy, AI Kosovo, pour qu'elles acqui\u00e8rent des connaissances, acqui\u00e8rent de nouvelles comp\u00e9tences et r\u00e9alisent leurs r\u00eaves. Notre vision s'\u00e9tend au-del\u00e0 de l'horizon, o\u00f9 chaque fille peut s'\u00e9panouir dans un environnement favorable, atteignant son plein potentiel dans un paysage de progr\u00e8s et d'opportunit\u00e9s.\r\n\r\n<strong>Quel est notre objectif ?<\/strong>\r\n\r\nDonnez-lui du pouvoir\u00a0! constitue une lueur d\u2019espoir pour les filles issues de milieux ruraux et marginalis\u00e9s. Nous avons pour mission de briser les barri\u00e8res et d\u2019ouvrir les portes aux opportunit\u00e9s. Gr\u00e2ce \u00e0 des cours STEM de haute qualit\u00e9 et au mentorat de femmes qui r\u00e9ussissent, nous ouvrons la voie \u00e0 plus de 100 000 filles du Kosovo \u00e2g\u00e9es de 11 \u00e0 18 ans pour qu'elles deviennent les leaders et les actrices du changement de demain. Il ne s'agit pas seulement d'\u00e9ducation; il s'agit d'autonomisation, d'\u00e9galit\u00e9 et de transformation des vies.\r\n\r\n<strong>De quoi avons nous besoin?<\/strong>\r\n\r\nPour transformer notre vision en r\u00e9alit\u00e9, nous avons besoin de votre soutien. Vos contributions financeront des bourses d'\u00e9tudes pour 150 filles m\u00e9ritantes, leur offrant ainsi un acc\u00e8s \u00e0 l'\u00e9ducation, \u00e0 des ressources et \u00e0 des opportunit\u00e9s auparavant inaccessibles. Ces bourses couvriront les frais de scolarit\u00e9, le mat\u00e9riel p\u00e9dagogique et les ressources technologiques. Ensemble, nous pouvons garantir que chaque fille dispose des outils dont elle a besoin pour exceller dans les domaines STEM et au-del\u00e0.\r\n\r\n<strong>Budget<\/strong>\r\n<ul>\r\n \t<li>15 000 \u00e0 150 bourses (80 \u00e0 100 euros par bourse)<\/li>\r\n \t<li>1 000 - Publicit\u00e9 et promotion<\/li>\r\n \t<li>2 000 - Transport<\/li>\r\n \t<li>10\u00a0% pour la plateforme Kosovo Ideas<\/li>\r\n<\/ul>\r\nTotal = 20 000\r\n\r\n<strong>Objectif \u00e9tendu 1<\/strong>\r\n<ul>\r\n \t<li>8 000 - 100 bourses suppl\u00e9mentaires<\/li>\r\n \t<li>4\u00a0000\u00a0\u2013\u00a0Support \u00e9tendu pour les cours de niveau sup\u00e9rieur destin\u00e9s aux 50\u00a0filles les plus performantes<\/li>\r\n \t<li>2 000 - Journ\u00e9e des filles dans les TIC \u2013 mentorat, universit\u00e9 et salon de l'emploi<\/li>\r\n \t<li>1 400 - 10\u00a0% pour la plateforme KosovoIdeas<\/li>\r\n<\/ul>\r\nTotal = 15 000\r\n\r\n<strong>Comment le support nous aidera-t-il ?<\/strong>\r\n\r\nVotre don nous permettra de recruter des prestataires de formation locaux de haute qualit\u00e9 pour proposer une gamme de cours technologiques inspirants et r\u00e9pondant aux normes internationales \u00e0 150 filles de tout le Kosovo. Les offres de cours, propos\u00e9es \u00e0 prix r\u00e9duit par nos partenaires, seront accessibles aux filles de leurs communaut\u00e9s et enseign\u00e9es \u00e0 un niveau appropri\u00e9 \u00e0 leur \u00e2ge, leur exp\u00e9rience et leurs int\u00e9r\u00eats. Les filles qui excellent et se montrent prometteuses seront soutenues pour poursuivre des cours avanc\u00e9s.\r\n\r\n<strong><em>Votre soutien \u00e0 EmpowerHer\u00a0! n'est pas seulement un don ; c'est un catalyseur de changement.<\/em><\/strong>\r\n\r\nAvec votre aide, nous donnerons aux filles les moyens de poursuivre leurs passions, de surmonter les barri\u00e8res et de devenir des leaders dans leurs communaut\u00e9s. Ensemble, nous m\u00e8nerons un changement syst\u00e9mique, remettrons en question les st\u00e9r\u00e9otypes, plaiderons pour l'\u00e9galit\u00e9 et favoriserons une culture d'inclusion et d'autonomisation. Votre investissement ne se limite pas \u00e0 leur avenir\u00a0; c'est un investissement dans un monde plus brillant et plus inclusif pour nous tous.\r\n\r\n<strong>Message sp\u00e9cial\u00a0:<\/strong>\r\n\r\nCe mois-ci, nous vous invitons \u00e0 oublier votre caf\u00e9 quotidien et \u00e0 investir dans quelque chose de vraiment extraordinaire : les r\u00eaves des jeunes femmes en herbe. Un mois de sacrifice peut soutenir deux filles et leurs r\u00eaves technologiques. Ensemble, nous transformerons de petits choix en grandes opportunit\u00e9s, cr\u00e9ant ainsi un effet d'entra\u00eenement d'autonomisation et d'opportunit\u00e9s au Kosovo et au-del\u00e0.\r\n\r\n&nbsp;\r\n\r\n<strong>Project Team<\/strong>\r\n\r\n&nbsp;\r\n\r\n<img class=\"\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Teresa-Crawford.jpg\" width=\"115\" height=\"153\" \/>\u00a0 \u00a0 \u00a0<strong><img class=\"alignnone  wp-image-13234\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Kushtrim-Xhakli.jpg\" alt=\"\" width=\"123\" height=\"154\" \/>\u00a0 \u00a0 <img class=\"alignnone wp-image-13062\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Abetare-Gojani-Executive-Director.png\" alt=\"\" width=\"149\" height=\"153\" \/><\/strong>\u00a0 <img class=\"alignnone  wp-image-13258\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Adelina-Qarri-Senior-Program-Manager-1.png\" alt=\"\" width=\"148\" height=\"152\" \/>\u00a0 \u00a0 \u00a0\u00a0<img class=\"alignnone wp-image-13070\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Arbresha-Tuhina-Finance-Manager.png\" alt=\"\" width=\"149\" height=\"153\" \/>\u00a0 \u00a0<img class=\"alignnone wp-image-13078\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Dina-Spahija-Program-Manager.png\" alt=\"\" width=\"159\" height=\"160\" \/>\r\n\r\nTeresa Crawford\u00a0 \u00a0 \u00a0Kushtrim Xhakli\u00a0 \u00a0 \u00a0Abetare Gojani\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Adelina Qarri\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Arbresha Tuhina\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Dina Spahija\r\n\r\n<img class=\"alignnone wp-image-13082\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Miranada-Vula-Admin-and-Finance-Associate.png\" alt=\"\" width=\"141\" height=\"144\" \/> <img class=\"alignnone wp-image-13086\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Vlora-Shabiu-Program-Manager.png\" alt=\"\" width=\"146\" height=\"146\" \/> <strong><img class=\"alignnone  wp-image-13238\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Miranda-Korpuzi-scaled.jpg\" alt=\"\" width=\"217\" height=\"144\" \/> <img class=\"alignnone  wp-image-13242\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Adriatik-Llugiqi-scaled.jpg\" alt=\"\" width=\"216\" height=\"144\" \/> <img class=\"alignnone  wp-image-13250\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Loreta-Zharjani-scaled.jpg\" alt=\"\" width=\"217\" height=\"144\" \/><\/strong>\r\n\r\nMiranda Vula\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Vlora Shabiu\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Miranda Korpuzi\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Adriatik Llugiqi\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Loreta Zharjani\r\n\r\n<strong> <img class=\"alignnone  wp-image-13246\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Jetmire-Maloku.jpg\" alt=\"\" width=\"132\" height=\"132\" \/>\u00a0 \u00a0 \u00a0<\/strong>\r\n\r\nJetmire Maloku","post_title":"EmpowerHer!","post_excerpt":"EmpowerHer! Les bourses alimentent les r\u00eaves technologiques des filles au Kosovo, cr\u00e9ant une onde de renforcement et d'\u00e9galit\u00e9 des sexes dans les STEM.\r\n<div class=\"flex-1 overflow-hidden\">\r\n<div class=\"react-scroll-to-bottom--css-qlehz-79elbk h-full\">\r\n<div class=\"react-scroll-to-bottom--css-qlehz-1n7m0yu\">\r\n<div class=\"flex flex-col text-sm pb-9\">\r\n<div class=\"w-full text-token-text-primary\" data-testid=\"conversation-turn-5\">\r\n<div class=\"px-4 py-2 justify-center text-base md:gap-6 m-auto\">\r\n<div class=\"flex flex-1 text-base mx-auto gap-3 md:px-5 lg:px-1 xl:px-5 md:max-w-3xl lg:max-w-[40rem] xl:max-w-[48rem] group final-completion\">\r\n<div class=\"relative flex w-full flex-col agent-turn\">\r\n<div class=\"flex-col gap-1 md:gap-3\">\r\n<div class=\"mt-1 flex justify-start gap-3 empty:hidden\">\r\n<div class=\"text-gray-400 flex self-end lg:self-center items-center justify-center lg:justify-start mt-0 -ml-1 h-7 gap-[2px] visible\">\r\n<div class=\"flex\"><\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"pr-2 lg:pr-0\"><\/div>\r\n<\/div>\r\n<div class=\"absolute\">\r\n<div class=\"flex w-full gap-2 items-center justify-center\"><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"w-full pt-2 md:pt-0 dark:border-white\/20 md:border-transparent md:dark:border-transparent md:w-[calc(100%-.5rem)]\"><form class=\"stretch mx-2 flex flex-row gap-3 last:mb-2 md:mx-4 md:last:mb-6 lg:mx-auto lg:max-w-2xl xl:max-w-3xl\">\r\n<div class=\"relative flex h-full flex-1 flex-col\">\r\n<div class=\"absolute bottom-full left-0 right-0\"><\/div>\r\n<div class=\"flex w-full items-center\"><\/div>\r\n<\/div>\r\n<\/form><\/div>","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"empowerher","to_ping":"","pinged":"","post_modified":"2024-03-27 15:06:06","post_modified_gmt":"2024-03-27 14:06:06","post_content_filtered":"","post_parent":0,"guid":"https:\/\/kosovaideas.com\/?post_type=product&#038;p=13053","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":12895,"post_author":"1499","post_date":"2024-03-19 08:34:48","post_date_gmt":"2024-03-19 07:34:48","post_content":"<strong>Who we are?<\/strong>\r\n\r\nThe organization Kosovo Institute of Logopedics was founded in 2018 and has as its mission the promotion of speech therapy services in the educational facilities of Kosovo, aiming to ensure that every child has access to the treatment and assistance necessary for the development of communication skills. The organization is led by speech therapist Mrs. Ardita Uka-Rexha. We believe that every child has the right to a quality education and specialist support to reach their full potential. The Kosovo Institute of Logopedics counts 30+ projects, 258+ volunteers and currently the main projects are the installation of communication signs in parks in Kosovo and the provision of free speech therapy services in regular schools.\r\n\r\n<strong>What is our purpose?<\/strong>\r\n\r\nOur goal is to raise a fund of 4,400 EUR to continue and expand our speech therapy services in our community. Funds raised will be used to ensure the training of our staff, the improvement of our speech therapy cabinets and to provide necessary materials for the evaluation and treatment of children.\r\n\r\n<strong>What do we need?<\/strong>\r\n\r\nTo achieve our goal, we ask for your financial support to ensure that our speech therapy services are accessible to all children with articulation difficulties. Your help will help build an environment dedicated to the development of our children's communication skills and increase awareness of the importance of speech therapy in their education.\r\n\r\nPlease join us in this important mission to help our children communicate and help shape a society more aware of their needs.\r\n\r\n<em><strong>Thank you for your endless support!<\/strong><\/em>\r\n\r\n<strong>Budget for the Project<\/strong>\r\n\r\nSpecific assessment materials from Turn &amp; Talk\u00ae (superduperinc.com) \u20ac1,500\r\n\r\nSpeech therapy materials \u20ac2,000\r\n\r\nTransportation of volunteers \u20ac500\r\n\r\nFee 10% KOSOVAideas\r\n\r\n<strong>Total \u20ac4,440<\/strong>\r\n\r\n<strong>Project Team<\/strong>\r\n\r\n<img class=\"alignnone wp-image-12896\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Ardita-Uka-Rexha.jpg\" alt=\"\" width=\"100\" height=\"149\" \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img class=\"alignnone wp-image-12912\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Marigona-Kozmaqi.jpg\" alt=\"\" width=\"146\" height=\"146\" \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img class=\"alignnone wp-image-12900\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Charlotte-Hilker.jpg\" alt=\"\" width=\"86\" height=\"146\" \/>\u00a0 \u00a0 \u00a0 \u00a0<img class=\"alignnone wp-image-12908\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Ardea-Cakmaku.jpg\" alt=\"\" width=\"151\" height=\"147\" \/>\u00a0 \u00a0 \u00a0 <img class=\"\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2024\/03\/Albina-Kelmendi.jpg\" width=\"131\" height=\"148\" \/>\r\n\r\nArdita Uka-Rexha\u00a0 \u00a0 \u00a0 Marigona Kozmaqi\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Charlotte Hilker\u00a0 \u00a0 \u00a0 Ardea Cakmaku\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Albina Kelmendi","post_title":"Empower Voices, Transform Lives: Support Speech Therapy in Kosovo!","post_excerpt":"Kosovo Institute of Logopedics seeks 4,440 EUR to expand speech therapy services, aiding children's communication skills development. Join us in supporting this vital cause.\r\n\r\n&nbsp;\r\n\r\n&nbsp;","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"empower-voices-transform-lives-support-speech-therapy-in-kosovo","to_ping":"","pinged":"","post_modified":"2024-05-09 12:11:00","post_modified_gmt":"2024-05-09 11:11:00","post_content_filtered":"","post_parent":0,"guid":"https:\/\/kosovaideas.com\/?post_type=product&#038;p=12895","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":12694,"post_author":"1479","post_date":"2023-11-22 08:54:43","post_date_gmt":"2023-11-22 07:54:43","post_content":"<p style=\"text-align: justify;\"><strong>Qui sommes-nous ? <\/strong><\/p>\r\n<p style=\"text-align: justify;\">L'ONG Projet 5 Cents, fond\u00e9e en 2013, est une organisation qui organise chaque ann\u00e9e le mini-marathon bien connu \"Cours P\u00e8re No\u00ebl Cours\". L'objectif de ce mini-marathon est de vendre des costumes du P\u00e8re No\u00ebl, qui seront port\u00e9s par les participants du mini-marathon, sans distinction d'\u00e2ge et de genre. Les fonds collect\u00e9s seront d\u00e9di\u00e9s aux familles dans le besoin et aux enfants atteints de maladies graves.<\/p>\r\n<p style=\"text-align: justify;\">Initialement, le mini-marathon \"Cours P\u00e8re No\u00ebl Cours\" a commenc\u00e9 avec seulement 100 P\u00e8res No\u00ebl, aidant environ 60 familles. Au fil des ans, ce nombre a augment\u00e9 pour atteindre sa 8e ann\u00e9e d'organisation, o\u00f9 ce mini-marathon est devenu une tradition et un \u00e9v\u00e9nement important pour la capitale. Cette ann\u00e9e, 3000 P\u00e8res No\u00ebl participeront au mini-marathon.<\/p>\r\n<p style=\"text-align: justify;\">Avec l'augmentation du nombre de participants, il y a aussi une opportunit\u00e9 accrue d'aider non seulement les familles dans le besoin, mais aussi les enfants souffrant de maladies graves et trait\u00e9s \u00e0 l'h\u00f4pital p\u00e9diatrique du Centre clinique universitaire du Kosovo, en particulier dans le service d'h\u00e9matologie-oncologie de cette clinique.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Quel est notre objectif ?<\/strong><\/p>\r\n<p style=\"text-align: justify;\">Cette ann\u00e9e, l'ONG 5 Cents a d\u00e9cid\u00e9 de lever des fonds sp\u00e9cifiquement pour les enfants du service d'h\u00e9matologie-oncologie de l'h\u00f4pital p\u00e9diatrique gr\u00e2ce \u00e0 une campagne sur KOSOVAideas. L'objectif est d'all\u00e9ger les difficult\u00e9s auxquelles sont confront\u00e9s ces enfants et de rendre la nuit du changement de saison aussi agr\u00e9able que possible.<\/p>\r\n<p style=\"text-align: justify;\"><strong>De quoi avons-nous besoin ?<\/strong><\/p>\r\n<p style=\"text-align: justify;\">Gr\u00e2ce \u00e0 une communication continue avec la direction de l'h\u00f4pital p\u00e9diatrique, le service d'h\u00e9matologie-oncologie, nous avons identifi\u00e9 l'\u00e9quipement et les outils n\u00e9cessaires pour am\u00e9liorer les services de sant\u00e9 pour ces enfants. De plus, nous visons \u00e0 organiser une nuit du P\u00e8re No\u00ebl \u00e0 l'occasion de la c\u00e9l\u00e9bration du Nouvel An. L'\u00e9quipement et les outils comprennent 6 lits pour les m\u00e8res restant 24 heures avec leurs enfants, des jouets et des outils qui ont un impact sur la r\u00e9habilitation psychologique des enfants pendant le traitement, ainsi que des cadeaux pour le Nouvel An.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Comment votre soutien nous aidera-t-il ?<\/strong><\/p>\r\n<p style=\"text-align: justify;\">Votre contribution aura un impact significatif sur la vie et le traitement des enfants atteints de maladies graves, en fournissant un certain soulagement dans leur traitement et en apportant des sourires \u00e0 leurs visages lors du changement de saison. En permettant l'achat de 6 lits, vous aiderez les m\u00e8res d'enfants atteints de maladies graves \u00e0 avoir plus de facilit\u00e9 \u00e0 rester pr\u00e8s de leurs proches, car leur force donne de la force \u00e0 leurs petits.<\/p>\r\n<p style=\"text-align: justify;\">Pendant le traitement, les enfants font face \u00e0 diff\u00e9rentes peurs, de la peur des aiguilles pour la th\u00e9rapie aux autres difficult\u00e9s de leur parcours de gu\u00e9rison. Cette situation n\u00e9cessite des soins psychologiques particuliers, et votre aide en donnant des fonds pour acheter des jouets et des outils ayant un impact sur leur bien-\u00eatre psychologique pendant le traitement les aidera \u00e0 faire face plus facilement \u00e0 leur situation.<\/p>\r\n<p style=\"text-align: justify;\">Enfin, mais non moins important, votre aide et votre soutien pour permettre des cadeaux et une atmosph\u00e8re festive avec le P\u00e8re No\u00ebl lors du changement de saison ajouteront des sourires aux visages de ces enfants qui, cette nuit-l\u00e0, seront allong\u00e9s dans le service avec le seul souhait : UNE GU\u00c9RISON COMPL\u00c8TE !<\/p>\r\n<p style=\"text-align: justify;\">Budget pour le projet<\/p>\r\n<p style=\"text-align: justify;\">Lits \u2013 6 pi\u00e8ces 1 500 \u20ac<\/p>\r\n<p style=\"text-align: justify;\">Jouets divers 1 000 \u20ac<\/p>\r\n<p style=\"text-align: justify;\">Outils pour la r\u00e9habilitation psychologique - jouets sp\u00e9cifiques 1 000 \u20ac<\/p>\r\n<p style=\"text-align: justify;\">Cadeaux et mascottes pour la nuit du P\u00e8re No\u00ebl 1 000 \u20ac<\/p>\r\n<p style=\"text-align: justify;\">Frais de KOSOVAideas (10 %) 500 \u20ac<\/p>\r\n<p style=\"text-align: justify;\">Total 5 000,00 \u20ac<\/p>","post_title":"\"Soyez un P\u00e8re No\u00ebl pour les Enfants dans le Besoin - Soutenez 'Vrapo Babadimer' pour les Enfants \u00e0 la Clinique P\u00e9diatrique.\"","post_excerpt":"Le projet d'ONG \"5 Cents\" organise l'\u00e9v\u00e9nement \"Run Santa Run\" pour aider les familles et les enfants atteints de maladies graves.","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"soyez-un-pere-noel-pour-les-enfants-dans-le-besoin-soutenez-vrapo-babadimer-pour-les-enfants-a-la-clinique-pediatrique","to_ping":"","pinged":"","post_modified":"2024-03-19 08:58:39","post_modified_gmt":"2024-03-19 07:58:39","post_content_filtered":"","post_parent":0,"guid":"https:\/\/kosovaideas.com\/?post_type=product&#038;p=12694","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":12533,"post_author":"1470","post_date":"2023-10-02 08:23:32","post_date_gmt":"2023-10-02 07:23:32","post_content":"<strong>Arri\u00e8re-plan<\/strong>\r\n\r\nL'\u00c9cole sup\u00e9rieure d'art appliqu\u00e9 \u00ab Odhise Paskali \u00bb de Peja a \u00e9t\u00e9 fond\u00e9e en 1946. Depuis sa cr\u00e9ation jusqu'\u00e0 aujourd'hui, elle reste la seule institution du pays d\u00e9di\u00e9e \u00e0 l'enseignement des arts appliqu\u00e9s. Tous les professionnels artistiques de notre pays ont leurs racines dans cette \u00e9cole. Actuellement, l'\u00e9cole propose cinq cours en tant que fili\u00e8res sp\u00e9cialis\u00e9es dans l'enseignement professionnel secondaire : design textile et de mode, design d'int\u00e9rieur, design graphique, design c\u00e9ramique et direction de peinture. L'\u00e9cole accueille actuellement 300 \u00e9tudiants, avec 60 \u00e9tudiants inscrits dans chaque profil.\r\n\r\n<strong>Direction du design c\u00e9ramique<\/strong>\r\n\r\nActuellement, 60 \u00e9tudiants sont inscrits au programme de design c\u00e9ramique, dont 60 % sont des femmes. Le design c\u00e9ramique a acquis une importance significative en tant que profil en raison de l'int\u00e9r\u00eat croissant pour les inscriptions chaque ann\u00e9e.\r\n\r\nCe programme fonctionne au sein de deux ateliers bien \u00e9quip\u00e9s, offrant un environnement id\u00e9al pour le d\u00e9veloppement des \u00e9tudiants. Les \u00e9tudiants de ce cours cr\u00e9ent une vari\u00e9t\u00e9 d'\u0153uvres artistiques, notamment des accessoires d\u00e9coratifs, des vases, des plats, des sculptures et des r\u00e9pliques de divers artefacts. Beaucoup de ces r\u00e9pliques sont expos\u00e9es au mus\u00e9e du Kosovo. De plus, les \u00e9tudiants de ce programme ont particip\u00e9 activement \u00e0 de nombreuses expositions et ont pr\u00e9sent\u00e9 leurs \u0153uvres \u00e0 l'\u00e9tranger.\r\n\r\nCependant, un probl\u00e8me urgent est apparu concernant le manque de fours ad\u00e9quats pour cuire ces cr\u00e9ations en c\u00e9ramique. Actuellement, les \u00e9tudiants de ce programme travaillent avec un petit four qui ne r\u00e9unit pas les conditions n\u00e9cessaires au d\u00e9veloppement optimal de leurs comp\u00e9tences. L\u2019absence d\u2019un four adapt\u00e9, plus grand et r\u00e9guli\u00e8rement entretenu freine la progression et la formation de nombreux \u00e9tudiants. Par cons\u00e9quent, un nombre important de leurs projets restent inachev\u00e9s.\r\n\r\n<strong>Le but du projet<\/strong>\r\n\r\nCompte tenu de la r\u00e9ussite du cours de design c\u00e9ramique, du d\u00e9vouement des \u00e9tudiants dans leurs \u00e9tudes et de l'objectif de leur offrir les meilleures opportunit\u00e9s possibles d'exceller, l'objectif principal du projet est d'acqu\u00e9rir un nouveau four \u00e0 c\u00e9ramique.\r\n\r\nL'implantation d'un nouveau Four \u00e0 C\u00e9ramique am\u00e9liorerait incontestablement la qualit\u00e9 de la formation des \u00e9tudiants, attirerait potentiellement davantage d'\u00e9tudiants au programme et faciliterait la r\u00e9alisation de nombreux projets artistiques. De plus, \u00e9quiper l'\u00e9cole de ce four permettrait aux \u00e9tudiants de cr\u00e9er des \u0153uvres d'art qui pourraient am\u00e9liorer consid\u00e9rablement leur visibilit\u00e9 et leur performance dans les concours et expositions internationaux et favoriser la croissance de leurs comp\u00e9tences professionnelles.\r\n\r\n<strong>Comment votre soutien nous aidera-t-il ?<\/strong>\r\n\r\nLe co\u00fbt du nouveau four, environ 10 000 euros, repr\u00e9sente un d\u00e9fi financier important tant pour l'\u00e9cole que pour les familles des \u00e9l\u00e8ves. Votre soutien est essentiel \u00e0 la bonne r\u00e9alisation de ce projet. En participant \u00e0 la campagne de financement pour doter l'\u00e9cole d'un nouveau four \u00e0 poterie, vous aurez un impact direct sur plusieurs aspects critiques :\r\n\r\n<strong>\u00c9ducation de qualit\u00e9<\/strong>\u00a0: Votre soutien garantira que ces \u00e9tudiants re\u00e7oivent la formation professionnelle dont ils ont besoin pour exceller dans leur domaine, contribuant ainsi au d\u00e9veloppement d\u2019artistes c\u00e9ramistes hautement qualifi\u00e9s.\r\n\r\n<strong>Repr\u00e9sentation nationale<\/strong> : Avec votre aide, ces \u00e9tudiants disposeront des outils et des ressources n\u00e9cessaires pour repr\u00e9senter efficacement notre pays sur la sc\u00e8ne internationale, mettant en valeur le talent artistique et le potentiel du Kosovo.\r\n\r\n<strong>Impact g\u00e9n\u00e9rationnel<\/strong>\u00a0: Votre soutien profitera non seulement \u00e0 la g\u00e9n\u00e9ration actuelle d'\u00e9tudiants, mais laissera \u00e9galement un h\u00e9ritage aux g\u00e9n\u00e9rations futures int\u00e9ress\u00e9es \u00e0 poursuivre une carri\u00e8re dans la c\u00e9ramique. Cet investissement dans l\u2019\u00e9ducation a le potentiel de fa\u00e7onner le paysage artistique de la r\u00e9gion pour les ann\u00e9es \u00e0 venir.\r\n\r\nVotre contribution \u00e0 ce projet est inestimable et grandement appr\u00e9ci\u00e9e. Cela fera une diff\u00e9rence significative dans la vie de ces \u00e9tudiants et de la communaut\u00e9 artistique.\r\n\r\n<strong>Budget du projet<\/strong>\r\n\r\n<strong>\u00a0<\/strong>\r\n<table style=\"height: 179px;\" width=\"899\">\r\n<tbody>\r\n<tr>\r\n<td><strong>CAT\u00c9GORIE<\/strong><\/td>\r\n<td><strong>BUDGET TOTAL<\/strong><\/td>\r\n<\/tr>\r\n<tr>\r\n<td>Four \u00e0 poterie<\/td>\r\n<td>10000\u20ac<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>10\u00a0% de frais de carte de cr\u00e9dit, de virement bancaire et KOSOVA ideas<\/td>\r\n<td>1000\u20ac<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 11.000\u20ac<\/strong>\r\n\r\n<strong>\u00a0<\/strong><strong>Project Team<\/strong>\r\n\r\n&nbsp;\r\n\r\n<strong>\u00a0 <img class=\"alignnone wp-image-12492\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/09\/IMG_2216-scaled.jpg\" alt=\"\" width=\"166\" height=\"110\" \/> <\/strong><strong>\u00a0\u00a0\u00a0 <img class=\"alignnone wp-image-12496\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/09\/IMG_2220-scaled.jpg\" alt=\"\" width=\"168\" height=\"112\" \/>\u00a0 \u00a0 \u00a0 \u00a0 <img class=\"alignnone wp-image-12500\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/09\/IMG_2230-scaled.jpg\" alt=\"\" width=\"172\" height=\"114\" \/><\/strong>\r\n\r\n<strong>\u00a0 Kastriot Blakaj\u00a0<\/strong> \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <strong>\u00a0Blerina Bytyqi\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Soreja Adzajlic<\/strong>","post_title":"\"\u00c9tincelle de cr\u00e9ativit\u00e9 : Aidez-nous \u00e0 allumer l'avenir du lyc\u00e9e 'Odhise Paskali' !\"","post_excerpt":"\"Soutenez notre projet d'acquisition d'un nouveau four \u00e0 c\u00e9ramique pour l'\u00c9cole sup\u00e9rieure d'art appliqu\u00e9 'Odhise Paskali' \u00e0 Peja, au Kosovo. Votre contribution garantira une \u00e9ducation de qualit\u00e9 aux aspirants c\u00e9ramistes, leur permettant d'exceller dans leur domaine et de repr\u00e9senter le talent artistique du Kosovo \u00e0 l'\u00e9chelle internationale. Cet investissement profite non seulement aux \u00e9tudiants actuels, mais laisse \u00e9galement un h\u00e9ritage aux g\u00e9n\u00e9rations futures int\u00e9ress\u00e9es par la c\u00e9ramique. Rejoignez-nous pour fa\u00e7onner le paysage artistique de la r\u00e9gion et avoir un impact significatif sur la vie de ces \u00e9tudiants.","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"etincelle-de-creativite-aidez-nous-a-allumer-lavenir-du-lycee-odhise-paskali","to_ping":"","pinged":"","post_modified":"2023-10-02 08:41:50","post_modified_gmt":"2023-10-02 07:41:50","post_content_filtered":"","post_parent":0,"guid":"https:\/\/kosovaideas.com\/?post_type=product&#038;p=12533","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":11565,"post_author":"1426","post_date":"2023-05-23 13:11:12","post_date_gmt":"2023-05-23 12:11:12","post_content":"<h4><strong>Qui nous sommes?<\/strong><\/h4>\r\n<p style=\"text-align: justify;\">La Fondation de la Ligue des cr\u00e9ateurs kosovars \u2013 Kosova Makers League (KML) est une plateforme \u00e9ducative non formelle qui organise le plus grand concours de robotique pour les \u00e9coles \u00e9l\u00e9mentaires et autres \u00e9tablissements d'enseignement du Kosovo qui travaillent avec des enfants \u00e2g\u00e9s de 6 \u00e0 15 ans.<\/p>\r\n<p style=\"text-align: justify;\">En organisant le plus grand concours de robotique, KML donne l'opportunit\u00e9 \u00e0 tous les enfants sans distinction de faire les premiers pas dans le domaine de la robotique et de r\u00e9aliser diverses activit\u00e9s avec un focus sur les domaines STEAM (Science, Technologie, Ing\u00e9nierie, Art et Math\u00e9matiques).\r\n\u00c0 ce jour, KML a distribu\u00e9 un total de 2100 robots \u00e9ducatifs gratuits \u00e0 234 \u00e9tablissements d'enseignement dans 30 municipalit\u00e9s du Kosovo, dont plus de 4500 \u00e9tudiants et plus de 500 enseignants ont \u00e9t\u00e9 impliqu\u00e9s.<\/p>\r\n<p style=\"text-align: justify;\">Pendant quatre ann\u00e9es cons\u00e9cutives, au concours de robotique des robots \u00e9ducatifs mBot ont \u00e9t\u00e9 utilis\u00e9s, et depuis septembre 2022, la ligue a \u00e9t\u00e9 mise \u00e0 jour avec le nouvel appareil micro Maqueen Plus. Ce nouvel appareil est moins co\u00fbteux, propose une programmation dans deux langages de programmation et fonctionne via la carte micro bit, dont la plupart des \u00e9coles \u00e9l\u00e9mentaires publiques sont d\u00e9j\u00e0 \u00e9quip\u00e9es.\r\n\u00c9tant une organisation \u00e0 but non lucratif, KML a r\u00e9alis\u00e9 tout son soutien au fil des ans gr\u00e2ce \u00e0 divers dons fournis principalement par des donateurs \u00e9trangers.\r\nCette ann\u00e9e, le concours de robotique est soutenu par l'ambassade am\u00e9ricaine au Kosovo.<\/p>\r\n\r\n<h4 style=\"text-align: justify;\"><strong>Quel est notre objectif?<\/strong><\/h4>\r\n<p style=\"text-align: justify;\">Notre objectif principal est de fournir autant de robots \u00e9ducatifs que possible afin qu'ils puissent \u00eatre distribu\u00e9s gratuitement dans les \u00e9coles \u00e9l\u00e9mentaires publiques du Kosovo, r\u00e9alisant ainsi leur num\u00e9risation. Cela permettrait au plus grand nombre d'enfants d'\u00eatre impliqu\u00e9s dans une nouvelle approche de l'\u00e9ducation, o\u00f9 la technologie n'est utilis\u00e9e que comme un outil pour encourager chez les enfants la pens\u00e9e critique et cr\u00e9ative, e travail d'\u00e9quipe et la communication, comp\u00e9tences n\u00e9cessaires pour faire face aux d\u00e9fis du si\u00e8cle dans lequel nous vivons.<\/p>\r\n\r\n<h5 style=\"text-align: justify;\"><em><strong>A travers la campagne \"un robot pour chaque enfant\", nous visons \u00e0 \u00e9quiper au moins 50% des \u00e9coles primaires publiques du pays, afin qu'un maximum d'enfants de 6 \u00e0 15 ans puissent toucher au monde de la robotique.<\/strong><\/em><\/h5>\r\n<p style=\"text-align: justify;\">De cette mani\u00e8re, un environnement inclusif et sain sera cr\u00e9\u00e9 dans les \u00e9coles primaires publiques du pays, o\u00f9 les enfants, quels que soient leur sexe, leur \u00e2ge et leur origine ethnique, se sentiront libres d'explorer et d'\u00eatre inspir\u00e9s en tant que futurs leaders de la science et de la technologie.<\/p>\r\n<p style=\"text-align: justify;\"><strong>Comment votre soutien va-t-il nous aider?<\/strong><\/p>\r\n<p style=\"text-align: justify;\">\u00c0 ce jour, gr\u00e2ce \u00e0 des dons, KML a r\u00e9ussi \u00e0 fournir \u00e0 25 % des \u00e9coles \u00e9l\u00e9mentaires du Kosovo des robots \u00e9ducatifs gratuits, en les incluant dans notre concours \u00e9ducatif.\r\nGr\u00e2ce \u00e0 votre soutien, nous serons en mesure d'atteindre l'inclusion d'au moins 50 % du total des \u00e9coles primaires publiques du pays.\r\nC'est pourquoi notre fondation vous invite \u00e0 rejoindre la campagne \"un robot pour chaque enfant\" pour rendre cela possible ensemble. Nous vous sommes reconnaissants si vous d\u00e9cidez de contribuer, mais pas seulement, nous vous sommes reconnaissants si vous partagez notre campagne avec votre soci\u00e9t\u00e9.<\/p>\r\n\r\n<h4 style=\"text-align: justify;\"><strong>Budget<\/strong><\/h4>\r\n<img class=\"size-full wp-image-11657 alignleft\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/05\/Buxheti_ENG.png\" alt=\"\" width=\"1056\" height=\"244\" \/>\r\n<h3><\/h3>\r\n<h3><\/h3>\r\n<h3><\/h3>\r\n<h3><\/h3>\r\n<h3><\/h3>\r\n<h3><\/h3>\r\n<h3 style=\"text-align: center;\"><strong>OBJECTIFS AJOUT\u00c9S<\/strong><\/h3>\r\n<ul>\r\n \t<li style=\"text-align: justify;\">* Selon les statistiques du minist\u00e8re de l'\u00c9ducation du Kosovo, pour l'ann\u00e9e scolaire 2021\/22, 878 \u00e9coles publiques primaires et secondaires sont enregistr\u00e9es.<\/li>\r\n \t<li style=\"text-align: justify;\">* Dans le concours de robotique ouvert de la Kosova Makers League un total de 212 \u00e9coles primaires et secondaires inf\u00e9rieures publiques sont enregistr\u00e9es.<\/li>\r\n \t<li style=\"text-align: justify;\">* Afin d'atteindre l'objectif de num\u00e9risation de toutes les \u00e9coles primaires publiques du Kosovo, 666 \u00e9coles suppl\u00e9mentaires devraient \u00eatre incluses dans notre concours, \u00e9quip\u00e9es de robots \u00e9ducatifs gratuits.<\/li>\r\n \t<li style=\"text-align: justify;\">* Pour y parvenir, KML a pr\u00e9par\u00e9 deux objectifs suppl\u00e9mentaires en cas d'atteinte de l'objectif principal avec le budget susmentionn\u00e9.<\/li>\r\n<\/ul>\r\n<img class=\"size-full wp-image-11661 aligncenter\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/05\/Stretch-Goal-1.png\" alt=\"\" width=\"1056\" height=\"303\" \/>\r\n\r\n<img class=\"size-full wp-image-11665 aligncenter\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/05\/Stretch-Goal-2.png\" alt=\"\" width=\"1056\" height=\"303\" \/>\r\n<h3><\/h3>\r\n<h3 style=\"text-align: center;\"><strong>VOTRE CONTRIBUTION SI<\/strong><\/h3>\r\n<img class=\"aligncenter wp-image-11644 size-full\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/05\/Kontributi-e1685367397153.jpg\" alt=\"\" width=\"1042\" height=\"844\" \/>\r\n\r\n&nbsp;\r\n<h3 style=\"text-align: center;\"><strong> ROBOT MICRO:MAQUEEN PLUS<\/strong><\/h3>\r\n<img class=\"size-full wp-image-11556 aligncenter\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/05\/micro-Maqueen-Plus-robot-1.gif\" alt=\"\" width=\"1080\" height=\"1080\" \/>\r\n<h3><\/h3>\r\n<h3><\/h3>\r\n<h3 style=\"text-align: center;\"><strong>DATE LIMITE\r\n<img class=\"size-full wp-image-11677 aligncenter\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/05\/Timeline_Kosova-Makers-League-2023-2024-1.png\" alt=\"\" width=\"1024\" height=\"768\" \/>\r\n<\/strong><\/h3>\r\n&nbsp;\r\n<h3 style=\"text-align: center;\"><strong> KOSOVA MAKERS LEAGUE \u00c9QUIPE\r\n<\/strong><\/h3>\r\n<img class=\" wp-image-11673 aligncenter\" src=\"https:\/\/kosovaideas.com\/wp-content\/uploads\/2023\/05\/Team_Kosova-Makers-League.png\" alt=\"\" width=\"963\" height=\"220\" \/>","post_title":"Un robot pour chaque enfant!","post_excerpt":"\"Un robot pour chaque enfant\" vise \u00e0 num\u00e9riser les \u00e9coles \u00e9l\u00e9mentaires publiques du Kosovo.","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"un-robot-pour-chaque-enfant","to_ping":"","pinged":"","post_modified":"2023-07-17 07:43:27","post_modified_gmt":"2023-07-17 06:43:27","post_content_filtered":"","post_parent":0,"guid":"https:\/\/kosovaideas.com\/product\/nje-robot-per-cdo-femije\/","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":7032,"post_author":"1427","post_date":"2023-03-12 20:02:39","post_date_gmt":"2023-03-12 19:02:39","post_content":"BONEVET Labs x Jeunes kosovars = comp\u00e9tences techniques tout en apprenant le recyclage et la conservation.\r\n\r\nBONEVET Labs est structur\u00e9 de mani\u00e8re \u00e0 obtenir des r\u00e9sultats durables et \u00e0 long terme sur la protection de l'environnement et la r\u00e9duction de l'utilisation du plastique. Cet objectif sera atteint gr\u00e2ce \u00e0 l'int\u00e9gration de la composante d'apprentissage par projet et \u00e0 l'encouragement des activit\u00e9s pratiques tout au long des ateliers pr\u00e9vus.\r\n\r\n&nbsp;\r\n\r\n<strong>Qui sommes-nous?<\/strong>\r\n\r\nBONEVET Prishtina en collaboration avec\u00a0<a href=\"https:\/\/manifesta14.org\/participant\/driant-zeneli\/\">Driant Zeneli<\/a>\u00a0(artiste albanais), travaillent ensemble dans un projet passionnant intitul\u00e9 \"Les animaux. Il \u00e9tait une fois... dans un pr\u00e9sent\". Ce projet sera pr\u00e9sent\u00e9 \u00e0 la Biennale Manifesta, l'une des plus c\u00e9l\u00e8bres biennales d'Europe. L'id\u00e9e de cette collaboration est de pr\u00e9senter l'autruche (oiseau non volant) comme un d\u00e9fenseur de l'environnement qui r\u00e9utilise le plastique gaspill\u00e9 en objets et outils utiles. L'autruche elle-m\u00eame sera construite par BONEVET, alors que des caract\u00e9ristiques suppl\u00e9mentaires, comme le mouvement de la queue et du cou, seront ajout\u00e9es. BONEVET recyclera les d\u00e9chets plastiques tout au long de l'exposition, en utilisant un broyeur,\u00a0une extrudeuse de filaments et quatre imprimantes 3D.\u00a0Les jeunes qui participeront \u00e0 ce laboratoire pendant les heures d'ouverture de la biennale, seront form\u00e9s \u00e0 l'utilisation d'une imprimante 3D et d'un logiciel de conception, et seront encourag\u00e9s \u00e0 r\u00e9duire leur consommation de plastique au quotidien.\r\n\r\nCes ateliers se d\u00e9rouleront dans un environnement s\u00fbr, dans l'espace de la biennale. Les activit\u00e9s propos\u00e9es comprendront des tables rondes, des projets de bricolage, la conception et l'impression 3D. Cet espace sera \u00e9galement utilis\u00e9 pour projeter des films et des documentaires sur le r\u00e9chauffement de la plan\u00e8te et le changement climatique.\r\n\r\n&nbsp;\r\n\r\n<strong>Quel est notre objectif?<\/strong>\r\n\r\nGr\u00e2ce \u00e0 ce projet, plus de 150 jeunes dans tout le pays auront la possibilit\u00e9 de travailler avec des imprimantes 3D, des logiciels de conception 3D et d'apprendre le recyclage en pratique. Il a \u00e9t\u00e9 prouv\u00e9 que l'apprentissage par projet a un rendement \u00e9lev\u00e9 des investissements dans la communaut\u00e9. C'est pourquoi nous pensons que ce projet donnera une impulsion consid\u00e9rable au secteur de l'environnement ici au Kosovo.\r\n\r\n&nbsp;\r\n\r\n<strong>Comment votre soutien va-t-il nous aider?<\/strong>\r\n\r\nAvec votre aide, nous pourrons acheter le mat\u00e9riel n\u00e9cessaire pour pr\u00e9parer techniquement l'espace pour le processus de recyclage. Nous allons acheter un protocycler, qui transformera le plastique broy\u00e9 en un filament qui pourra ensuite \u00eatre utilis\u00e9 dans des imprimantes 3D.\u00a0 En plus de cela, d'autres \u00e9quipements \u00e9lectroniques seront achet\u00e9s pour rendre fonctionnels les installations et les \u0153uvres d'art. Pour plus d'informations sur Manifesta, lisez ici:\u00a0<a href=\"https:\/\/manifesta14.org\/\">www.manifesta14.org<\/a>\r\n\r\n&nbsp;\r\n\r\n<strong>Budget<\/strong>\r\n<table width=\"661\">\r\n<tbody>\r\n<tr>\r\n<td width=\"37\">1)<\/td>\r\n<td width=\"501\">Protocycler plus grindless<\/td>\r\n<td width=\"123\">\u00a0 \u00a0 \u20ac\u00a0 \u00a0 \u00a0 \u00a0 \u00a03,635.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>2)<\/td>\r\n<td>Plexi transparent\u00a08 mm 205x305 cm<\/td>\r\n<td>\u00a0 \u00a0 \u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 270.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>3)<\/td>\r\n<td>Cadre et plaques en m\u00e9tal<\/td>\r\n<td>\u00a0 \u00a0 \u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 200.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>4)<\/td>\r\n<td>Servomoteurs + \u00e9quipement \u00e9lectronique<\/td>\r\n<td>\u00a0 \u00a0 \u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 280.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>5)<\/td>\r\n<td>Taxes + frais<\/td>\r\n<td>\u00a0 \u00a0 \u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 115.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>6)<\/td>\r\n<td>10% de frais de carte de cr\u00e9dit, de virement bancaire et de plateforme<\/td>\r\n<td>\u00a0 \u00a0 \u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 500.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td><\/td>\r\n<td><strong>Total<\/strong><\/td>\r\n<td><strong>\u00a0 \u00a0 \u20ac\u00a0 \u00a0 \u00a0 \u00a0 \u00a05,000.00<\/strong><\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>","post_title":"BONEVET Labs x MANIFESTA","post_excerpt":"BONEVET Labs x kosovarische Jugendliche = technische F\u00e4higkeiten beim Lernen \u00fcber Recycling und Naturschutz.","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"bonevet-labs-x-manifesta","to_ping":"","pinged":"","post_modified":"2023-07-17 10:12:30","post_modified_gmt":"2023-07-17 09:12:30","post_content_filtered":"","post_parent":0,"guid":"https:\/\/ki2023.kosovaideas.com\/product\/bonevet-labs-x-manifesta\/","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":7244,"post_author":"1428","post_date":"2022-03-30 13:53:44","post_date_gmt":"2022-03-30 12:53:44","post_content":"<strong>Qui sommes nous?<\/strong>\r\n\r\n&nbsp;\r\n\r\nL'ONG SAKUNTALA a \u00e9t\u00e9 cr\u00e9\u00e9e en 2008 dans le but de cr\u00e9er un environnement stable au Kosovo pour l'int\u00e9gration des communaut\u00e9s minoritaires afin de repr\u00e9senter leur position, les droits de l'homme et de promouvoir les valeurs d'\u00e9galit\u00e9, d'inclusion sociale et de d\u00e9veloppement socio-\u00e9conomique pour tous les individus et groupes. ind\u00e9pendamment de leur appartenance ethnique, religieuse, sexuelle ou sociale. Entre autres, l'organisation a \u00e9t\u00e9 cr\u00e9\u00e9e pour promouvoir et pr\u00e9server les int\u00e9r\u00eats de la diversit\u00e9, les valeurs d'\u00e9galit\u00e9, de dialogue et de solidarit\u00e9.\r\n\r\n&nbsp;\r\n\r\n<strong>Quel est notre objectif?<\/strong>\r\n\r\n&nbsp;\r\n\r\nLes femmes des communaut\u00e9s rom, ashkali et \u00e9gyptienne sont victimes de discrimination, ont un acc\u00e8s limit\u00e9 \u00e0 l'emploi, \u00e0 l'\u00e9ducation et aux soins de sant\u00e9, et ce ne sont l\u00e0 que quelques-uns des facteurs qui contribuent \u00e0 l'oppression et \u00e0 la marginalisation profond\u00e9ment enracin\u00e9es des femmes des minorit\u00e9s. communaut\u00e9s. Le manque de scolarisation et la discrimination sexuelle et ethnique \u00e0 l'encontre de ces femmes sont des obstacles importants \u00e0 leur int\u00e9gration dans la soci\u00e9t\u00e9 kosovare.\r\n\r\n&nbsp;\r\n\r\nLe but de ce projet est donc:\r\n<ol>\r\n \t<li>Am\u00e9liorer les comp\u00e9tences des femmes et des filles roms gr\u00e2ce \u00e0 une formation professionnelle aux activit\u00e9s artisanales.<\/li>\r\n \t<li>Am\u00e9liorer le d\u00e9veloppement socio-\u00e9conomique, promouvoir la cr\u00e9ativit\u00e9 traditionnelle et renforcer leur coop\u00e9ration avec le march\u00e9 priv\u00e9, les ONG f\u00e9minines, les institutions culturelles et locales.<\/li>\r\n<\/ol>\r\n&nbsp;\r\n\r\nGr\u00e2ce aux activit\u00e9s susmentionn\u00e9es, leurs comp\u00e9tences en mati\u00e8re d'artisanat seront am\u00e9lior\u00e9es par une formation professionnelle, suivie de la promotion de leurs produits et de leur vente sur le march\u00e9 priv\u00e9, am\u00e9liorant ainsi leurs conditions de vie. Ce sera une force motrice pour la promotion et la pr\u00e9servation des valeurs culturelles ainsi que le d\u00e9veloppement socio-\u00e9conomique des femmes et des filles roms. Ces formations ont eu lieu auparavant et ont connu un grand succ\u00e8s, mais nous voulons r\u00e9aliser quelque chose \u00e0 plus long terme et que les femmes ne s'arr\u00eatent pas apr\u00e8s avoir termin\u00e9 la formation, mais continuent \u00e0 promouvoir leur travail. Par cons\u00e9quent, une exposition avec ces objets artisanaux sera organis\u00e9e, avec la participation de la soci\u00e9t\u00e9 civile, des ONG culturelles, des institutions locales, du secteur priv\u00e9 et des associations d'artisans afin de promouvoir les produits artisanaux des femmes et des filles roms.\r\n\r\n&nbsp;\r\n\r\n<strong>Comment votre soutien va-t-il nous aider?<\/strong>\r\n\r\n<strong>\u00a0<\/strong>\r\n\r\nAvec les fonds qui seront r\u00e9colt\u00e9s, le mat\u00e9riel n\u00e9cessaire sera achet\u00e9 pour d\u00e9marrer la formation avec ces femmes et jeunes filles de la communaut\u00e9 rom. Ce projet renforcera leurs comp\u00e9tences en mati\u00e8re d'artisanat traditionnel gr\u00e2ce \u00e0 la formation professionnelle. Des femmes \u00e2g\u00e9es de 18 \u00e0 50 ans seront s\u00e9lectionn\u00e9es pour les activit\u00e9s. La formation sera organis\u00e9e dans la municipalit\u00e9 de Prizren, \u00e0 l'Institut Yunus Emre, un institut turc qui a sa branche au Kosovo, \u00e0 Prizren et \u00e0 Peja. La formation durera 4-5 mois et sera anim\u00e9e par des animatrices, des formatrices qui prodigueront des conseils sur l'autonomisation des femmes \u00e0 travers l'artisanat. Les b\u00e9n\u00e9ficiaires directs de ce projet sont les femmes et les filles de la communaut\u00e9 rom de la municipalit\u00e9 de Prizren.\r\n\r\n<b>Budget<\/b>\r\n\r\nTotal\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 2,400.00\r\n<table width=\"679\">\r\n<tbody>\r\n<tr>\r\n<td width=\"33\">1)<\/td>\r\n<td width=\"523\">Mat\u00e9riel (tissu) pour la peinture<\/td>\r\n<td width=\"123\">\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 400.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>2)<\/td>\r\n<td>Peintures acryliques pour la peinture sur verre et mat\u00e9riaux<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 200.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>3)<\/td>\r\n<td>Cadres<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 150.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>4)<\/td>\r\n<td>Miroirs et contreplaqu\u00e9<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 190.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>5)<\/td>\r\n<td>Fleurs d\u00e9coratives s\u00e9ch\u00e9es<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 200.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>6)<\/td>\r\n<td>Plats en verre avec supports, vases d\u00e9coratifs et bougeoirs<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 120.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>7)<\/td>\r\n<td>Fil \u00e0 broder et fil d'or<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 200.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>8)<\/td>\r\n<td>Dentelle, paniers, papier pour la conception, etc.<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 150.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>9)<\/td>\r\n<td>Frais de transport<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 150.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>10)<\/td>\r\n<td>Frais d'exposition<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 300.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>11)<\/td>\r\n<td>Banners<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 100.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>12)<\/td>\r\n<td>10% de frais de carte de cr\u00e9dit, de virement bancaire et de plateforme<\/td>\r\n<td>\u00a0\u20ac\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 240.00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td><\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>","post_title":"Fuqizimi i grave dhe vajzave rome p\u00ebrmes artizanatit","post_excerpt":"<div class=\"description\">\r\n<div class=\"description\">Ce projet renforcera les comp\u00e9tences des femmes et des filles roms en mati\u00e8re d'artisanat traditionnel gr\u00e2ce \u00e0 la formation professionnelle.<\/div>\r\n<\/div>","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"fuqizimi-i-grave-dhe-vajzave-rome-permes-artizanatit","to_ping":"","pinged":"","post_modified":"2023-07-17 10:16:02","post_modified_gmt":"2023-07-17 09:16:02","post_content_filtered":"","post_parent":0,"guid":"https:\/\/ki2023.kosovaideas.com\/product\/fuqizimi-i-grave-dhe-vajzave-rome-permes-artizanatit\/","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":7248,"post_author":"1429","post_date":"2021-11-24 13:58:07","post_date_gmt":"2021-11-24 12:58:07","post_content":"<strong>Qui sommes-nous?<\/strong>\r\n\r\nJe m'appelle Jimmy Mustafa et je fais partie d'un groupe de musique Rom appel\u00e9 \"Jimmy Mustafa Band\" de Plementina. Plemetina est une petite ville de la municipalit\u00e9 d'Obiliq, \u00e0 Prishtina. C'est un lieu multiethnique o\u00f9 cohabitent Albanais, Serbes, Roms, Ashkali et autres. En 2009, six jeunes Roms ont uni leurs talents pour cr\u00e9er un genre diff\u00e9rent de musique traditionnelle rom et d'autres styles de musique. Nous avons deux albums studio, le premier intitul\u00e9\u00a0<strong>\"Posvetime\" (D\u00e9di\u00e9<\/strong>) avec 10 titres et le second album \"<strong>Romane Bajrakja\" (Drapeaux Roms)<\/strong>\u00a0avec 11 chansons originales. En 2018 et 2019, le groupe a effectu\u00e9 une tourn\u00e9e en Suisse et en Allemagne.\r\n\r\nJ'ai \u00e9galement produit la musique de neuf films documentaires sur les Roms, tels que : Jek Kham Jek Sel, Naci Palem Khere, Sar Thuv, Live, Auschvic en Pologne, Roki, etc. J'ai travaill\u00e9 avec des enfants en tant que professeur, leur apprenant \u00e0 jouer d'instruments tels que la guitare, le cajon, le piano, et leur donnant des cours de chant. Je suis le fondateur d'un centre pour les enfants et les jeunes, avec des amis du Kosovo et de la Suisse, appel\u00e9 Music 4 All.\r\n\r\n<strong>Quel est notre objectif?<\/strong>\r\n\r\nNotre centre \"Music 4 ALL\" sera une initiative pionni\u00e8re et des plus abouties qui permettra aux enfants et aux jeunes d'\u00e9largir leurs activit\u00e9s musicales et artistiques et de se d\u00e9couvrir de nouveaux talents. Music 4 ALL \u00e9tait et restera un second foyer pour chaque enfant et chaque jeune. Tous ceux qui aiment l'art de la musique et qui veulent apprendre ou am\u00e9liorer le chant et la pr\u00e9formation aux \u00e9tudes feront partie de ce projet.\r\n\r\nMusic 4 ALL proposera des cours individuels et collectifs de musique classique et moderne tels que le piano, la clarinette, le cajon, la guitare, le chant, le sport, l'enregistrement vid\u00e9o, le montage vid\u00e9o et d'autres activit\u00e9s n\u00e9cessaires aux enfants et aux jeunes. Il y aura \u00e9galement une classe d'art\/peinture o\u00f9 les enfants cr\u00e9eront de l'art \u00e0 travers la musique avec notre aide.\r\n\r\nNous aurons \u00e9galement des ateliers, o\u00f9 des artistes seront invit\u00e9s \u00e0 partager leurs exp\u00e9riences avec tout le monde. Nous enregistrerons de la musique (chansons\/albums) et organiserons \u00e9galement des concerts\/\u00e9v\u00e9nements, o\u00f9 tout le monde sera le bienvenu.\r\n\r\n<strong>Comment votre soutien va-t-il nous aider?<\/strong>\r\n\r\nGr\u00e2ce \u00e0 votre soutien, nous donnerons aux enfants et aux jeunes de Plementina la possibilit\u00e9 de montrer leur talent en musique et en arts.\r\n\r\nNous organiserons les activit\u00e9s suivantes :\r\n<ul>\r\n \t<li>\u00c9ducation musicale<\/li>\r\n \t<li>Cours de piano<\/li>\r\n \t<li>Cours de clarinette<\/li>\r\n \t<li>Classes de chant\/voix<\/li>\r\n \t<li>Cours de guitare<\/li>\r\n \t<li>Cours de cajon<\/li>\r\n \t<li>Cours d'informatique<\/li>\r\n \t<li>Cin\u00e9ma (diffusion de films)<\/li>\r\n \t<li>Cours de peinture<\/li>\r\n<\/ul>\r\nIl y aura cinq cours proposant des ateliers de guitare, clarinette, piano, cajon et chant. Ces cours seront dispens\u00e9s afin d'enrichir et d'\u00e9tendre la partie pratique, permettant aux candidats d'acqu\u00e9rir les notes et les comp\u00e9tences de base dans les instruments ainsi que le chant.\r\n\r\n<strong>Budget<\/strong>\r\n\r\nTotal\u00a0\u20ac 5\u00a0000,00\r\n<table width=\"509\">\r\n<tbody>\r\n<tr>\r\n<td width=\"29\">1)<\/td>\r\n<td width=\"388\">\u00a0Mat\u00e9riel p\u00e9dagogique<\/td>\r\n<td width=\"92\">\u00a0\u20ac 200,00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>2)<\/td>\r\n<td>\u00a0Mat\u00e9riel p\u00e9dagogique<\/td>\r\n<td>\u00a0\u20ac 120,00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>3)<\/td>\r\n<td>\u00a0Mat\u00e9riel artistique pour les enfants<\/td>\r\n<td>\u00a0\u20ac 150,00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>4)<\/td>\r\n<td>\u00a0Collations pour les enfants<\/td>\r\n<td>\u00a0\u20ac 500,00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>5)<\/td>\r\n<td>\u00a0Transport hebdomadaire de Plementina \u00e0 Obiliq et Prishtina<\/td>\r\n<td>\u00a0\u20ac 600,00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>6)<\/td>\r\n<td>\u00a0PC pour le montage<\/td>\r\n<td>\u00a0\u20ac 800,00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>7)<\/td>\r\n<td>\u00a0Appareil photo<\/td>\r\n<td>\u00a0\u20ac 750,00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>8)<\/td>\r\n<td>\u00a0\u00c9v\u00e9nements suppl\u00e9mentaires, concerts<\/td>\r\n<td>\u00a0\u20ac 880,00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>9)<\/td>\r\n<td>\u00a0Chauffage<\/td>\r\n<td>\u00a0\u20ac 500,00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td>10)<\/td>\r\n<td>\u00a010% de frais de carte de cr\u00e9dit, de virement bancaire et de plateforme<\/td>\r\n<td>\u00a0\u20ac 500,00<\/td>\r\n<\/tr>\r\n<tr>\r\n<td><\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>","post_title":"MUSIC 4 ALL","post_excerpt":"<div class=\"description\">MUSIC 4 ALL est une \u00e9cole de musique \u00e0 Plementina. Nous offrons des cours gratuits pour tous les enfants et les jeunes.<\/div>\r\n<span style=\"font-weight: 400;\">\u00a0<\/span>","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"music-4-all","to_ping":"","pinged":"","post_modified":"2023-07-17 10:21:51","post_modified_gmt":"2023-07-17 09:21:51","post_content_filtered":"","post_parent":0,"guid":"https:\/\/ki2023.kosovaideas.com\/product\/music-4-all\/","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"}],"_links":{"self":[{"href":"https:\/\/kosovaideas.com\/fr\/wp-json\/wp\/v2\/product\/7248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kosovaideas.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kosovaideas.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/kosovaideas.com\/fr\/wp-json\/wp\/v2\/users\/1429"}],"replies":[{"embeddable":true,"href":"https:\/\/kosovaideas.com\/fr\/wp-json\/wp\/v2\/comments?post=7248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kosovaideas.com\/fr\/wp-json\/wp\/v2\/media\/6343"}],"wp:attachment":[{"href":"https:\/\/kosovaideas.com\/fr\/wp-json\/wp\/v2\/media?parent=7248"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kosovaideas.com\/fr\/wp-json\/wp\/v2\/product_brand?post=7248"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kosovaideas.com\/fr\/wp-json\/wp\/v2\/product_cat?post=7248"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kosovaideas.com\/fr\/wp-json\/wp\/v2\/product_tag?post=7248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}